{"id":11833,"date":"2020-02-21T22:46:21","date_gmt":"2020-02-21T21:46:21","guid":{"rendered":"https:\/\/www.richter.ca\/?p=11833"},"modified":"2021-07-23T16:16:09","modified_gmt":"2021-07-23T14:16:09","slug":"previsions-economiques-pour-2020","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/","title":{"rendered":"Pr\u00e9visions \u00e9conomiques pour 2020"},"content":{"rendered":"<h2 style=\"font-size: 35px;\">Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.<\/h2>\n<p>Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais bien deux\u00a0des dirigeants les plus renomm\u00e9s de la Banque\u00a0TD, <a href=\"https:\/\/economics.td.com\/about-us\" target=\"_blank\" rel=\"noopener noreferrer\">M<sup>me<\/sup>\u00a0Beata\u00a0Caranci, \u00e9conomiste en chef<\/a> et <a href=\"https:\/\/www.linkedin.com\/in\/brian-depratto-11b06810\/\" target=\"_blank\" rel=\"noopener noreferrer\">M.\u00a0Brian\u00a0DePratto, directeur et \u00e9conomiste principal<\/a>, qui ont respectivement particip\u00e9 \u00e0 nos \u00e9v\u00e9nements de Toronto et de Montr\u00e9al. Ils ont ainsi pu partager avec les participants leurs r\u00e9flexions sur l\u2019ann\u00e9e \u00e0 venir.<\/p>\n<h3>PERSPECTIVE MONDIALE<\/h3>\n<ul>\n<li>Selon le tableau de la pr\u00e9vision consensuelle de la croissance mondiale de Bloomberg, nous assisterons \u00e0 une baisse de la croissance mondiale, qui passera de 3,3\u00a0% \u00e0 3,0\u00a0%. \u00c0 la fin de 2019, les perspectives \u00e9conomiques de certains pays ont \u00e9t\u00e9 revues \u00e0 la baisse en raison de conflits commerciaux, d\u2019obstacles et d\u2019autres facteurs. Ces rajustements contrastent toutefois avec l\u2019optimisme ambiant sur les march\u00e9s.<\/li>\n<li>Alors que la confiance des investisseurs demeure forte et que les march\u00e9s pr\u00e9voient une hausse de la croissance, on ne sait pas exactement quelle r\u00e9gion progressera. L\u2019Allemagne a obtenu le meilleur rendement en 2019, mais devrait perdre du terrain en 2020. Les seuls march\u00e9s qui devraient conna\u00eetre une hausse sont ceux du Japon, des \u00c9tats-Unis et des pays \u00e9mergents. La croissance du Canada et de l\u2019Europe devrait se maintenir respectivement \u00e0 1,6\u00a0% et \u00e0 1,0\u00a0%.<\/li>\n<li>Jusqu\u2019\u00e0 maintenant, la demande des clients dans les \u00e9conomies d\u00e9velopp\u00e9es ne faiblit pas, et le secteur des services en particulier est tr\u00e8s solide malgr\u00e9 la baisse de la production industrielle.<\/li>\n<\/ul>\n<h3>PLEINS FEUX SUR LES \u00c9TATS-UNIS<\/h3>\n<ul>\n<li>L\u2019indice \u00e9conomique avanc\u00e9 de la Banque\u00a0TD, qui s\u2019appuie sur d\u2019importants indicateurs \u00e9conomiques, montre un <em>l\u00e9ger<\/em> Le secteur manufacturier est en perte de vitesse, mais pour l\u2019ensemble des \u00c9tats-Unis, le principal d\u00e9fi est l\u2019incertitude. Ce flou explique le fl\u00e9chissement des investissements<\/li>\n<li>Sur le plan commercial, il est difficile de pr\u00e9dire le d\u00e9nouement de l\u2019accord commercial entre la Chine et les \u00c9tats-Unis. \u00c0 l\u2019heure actuelle, la demande dans certains secteurs comme les produits manufactur\u00e9s et l\u2019\u00e9nergie est \u00e9norme, ce qui pousse les intervenants \u00e0 s\u2019interroger sur la capacit\u00e9 \u00e0 livrer la marchandise. Dans l\u2019ensemble, l\u2019accord ne vient pas changer la donne.<\/li>\n<li>Les taux hypoth\u00e9caires aux \u00c9tats-Unis ont aussi connu des hauts et des bas. Les taux d\u2019int\u00e9r\u00eat ont baiss\u00e9 en 2019, ce qui a engendr\u00e9 une l\u00e9g\u00e8re hausse des ventes de maisons unifamiliales. Cette situation est encourageante pour les intervenants des secteurs de la construction et des mat\u00e9riaux, et pourrait avoir un effet b\u00e9n\u00e9fique sur les ventes d\u2019autres biens de consommation discr\u00e9tionnaire, comme l\u2019ameublement, les v\u00e9hicules r\u00e9cr\u00e9atifs, etc.<\/li>\n<li>Les salaires sont \u00e9galement en hausse, tout particuli\u00e8rement ceux des emplois bien r\u00e9mun\u00e9r\u00e9s. Dans l\u2019ensemble, les effets de la crise de 2008 semblent s\u2019estomper.<\/li>\n<\/ul>\n<h3>SITUATION AU CANADA<\/h3>\n<ul>\n<li>La croissance du PIB au Canada en 2019 a \u00e9t\u00e9 plut\u00f4t in\u00e9gale\u00a0: le PIB a grimp\u00e9 en fl\u00e8che au deuxi\u00e8me\u00a0trimestre pour ralentir au quatri\u00e8me\u00a0trimestre, en raison de la gr\u00e8ve ferroviaire et d\u2019autres \u00e9l\u00e9ments perturbateurs, ce qui se traduit par un rythme moins soutenu en 2020. Mais les pr\u00e9visions indiquent que la croissance devrait reprendre aux troisi\u00e8me et quatri\u00e8me\u00a0trimestres de 2020 et se r\u00e9tablir au taux habituel de 2,0\u00a0%.<\/li>\n<li>\u00c0 l\u2019\u00e9chelle r\u00e9gionale, contre toute attente, l\u2019\u00cele-du-Prince-\u00c9douard devrait conna\u00eetre, et de loin, la plus grande croissance parmi toutes les provinces, pour rel\u00e9guer le Qu\u00e9bec en deuxi\u00e8me\u00a0place. L\u2019\u00cele-du-Prince-\u00c9douard domine ce palmar\u00e8s principalement en raison de la croissance de sa population. Le Qu\u00e9bec est bon deuxi\u00e8me gr\u00e2ce \u00e0 la vigueur du march\u00e9 de l\u2019emploi au cours des derni\u00e8res ann\u00e9es et aux co\u00fbts d\u2019emprunt qui sont inf\u00e9rieurs \u00e0 ceux de l\u2019Ontario. La croissance en Colombie-Britannique et en Ontario est conforme \u00e0 la moyenne nationale, alors que dans les r\u00e9gions de l\u2019Atlantique et des Prairies, le rythme est plus lent.<\/li>\n<li>La Banque\u00a0TD s\u2019attend \u00e0 ce que la Banque du Canada proc\u00e8de \u00e0 des baisses de taux, compte tenu des risques actuels de repli \u00e9conomique. Selon TD, il ne s\u2019agit pas du d\u00e9but d\u2019une s\u00e9rie de baisses de taux ni d\u2019une situation inqui\u00e9tante, mais plut\u00f4t d\u2019une forme de rajustement des attentes. C\u2019est une occasion de g\u00e9rer les co\u00fbts d\u2019emprunt \u00e0 long terme qui ont subi les contrecoups de la conjoncture mondiale, sans oublier les obstacles potentiels \u00e0 venir, notamment le coronavirus.<\/li>\n<li>M\u00eame si la croissance de la population a contribu\u00e9 \u00e0 stimuler l\u2019\u00e9conomie, on ne peut pas s\u2019y fier continuellement. De plus, m\u00eame si le nombre d\u2019emplois a connu de nouveaux sommets en 2019, il a diminu\u00e9 au cours du deuxi\u00e8me\u00a0semestre de l\u2019ann\u00e9e.<\/li>\n<li>Un aspect positif\u00a0: le logement, propuls\u00e9 par la croissance de la population et la solidit\u00e9 des march\u00e9s de l\u2019emploi.<\/li>\n<li>Les donn\u00e9es de base de 2020 sur les d\u00e9penses de consommation s\u2019\u00e9tabliront \u00e0 1,6\u00a0% (comme l\u2019an dernier) et seront influenc\u00e9es par l\u2019incertitude persistante sur le plan commercial, les ratios du service de la dette \u00e9lev\u00e9s et un faible taux d\u2019\u00e9pargne (1,7\u00a0%). Les d\u00e9penses de consommation sont en hausse de 2\u00a0%, la croissance de l\u2019emploi est ferme, les salaires ont augment\u00e9 d\u2019environ 4\u00a0% sur 12\u00a0mois, le march\u00e9 du logement rebondit et les taux obligataires se maintiennent \u00e0 leurs niveaux actuels.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Nous tenons \u00e0 remercier M<sup>me<\/sup>\u00a0Caranci et M.\u00a0DePratto d\u2019avoir pris le temps de participer aux \u00e9v\u00e9nements Pr\u00e9visions \u00e9conomiques et de nous avoir transmis des renseignements judicieux.<\/p>\n<p>Merci aux associ\u00e9s <a href=\"https:\/\/www.richter.ca\/fr\/experts\/mitchell-silverstein\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mitch Silverstein<\/a> et <a href=\"https:\/\/www.richter.ca\/fr\/experts\/giovanni-dimaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Johnny Di Maria<\/a> pour l&rsquo;organisation de ces \u00e9v\u00e9nements.<\/p>\n<p>&nbsp;<\/p>\n<p><em>*Les faits et les donn\u00e9es pr\u00e9sent\u00e9s ci-dessus sont des extraits traduits de la pr\u00e9sentation de M.\u00a0DePratto. \u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais bien deux\u00a0des dirigeants les plus renomm\u00e9s de la Banque\u00a0TD, Mme\u00a0Beata\u00a0Caranci, \u00e9conomiste en chef et M.\u00a0Brian\u00a0DePratto, directeur et \u00e9conomiste principal, qui ont respectivement particip\u00e9 \u00e0 nos \u00e9v\u00e9nements de Toronto et [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1371],"class_list":["post-11833","insights","type-insights","status-publish","hentry","insights-type-optimiser-vos-activites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9visions \u00e9conomiques pour 2020 - Richter<\/title>\n<meta name=\"description\" content=\"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9visions \u00e9conomiques pour 2020 - Richter\" \/>\n<meta property=\"og:description\" content=\"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T14:16:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/previsions-economiques-pour-2020\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/previsions-economiques-pour-2020\\\/\",\"name\":\"Pr\u00e9visions \u00e9conomiques pour 2020 - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2020-02-21T21:46:21+00:00\",\"dateModified\":\"2021-07-23T14:16:09+00:00\",\"description\":\"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/previsions-economiques-pour-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/previsions-economiques-pour-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/previsions-economiques-pour-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pr\u00e9visions \u00e9conomiques pour 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9visions \u00e9conomiques pour 2020 - Richter","description":"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9visions \u00e9conomiques pour 2020 - Richter","og_description":"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-07-23T14:16:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/","name":"Pr\u00e9visions \u00e9conomiques pour 2020 - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2020-02-21T21:46:21+00:00","dateModified":"2021-07-23T14:16:09+00:00","description":"Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD. Nous avons eu droit \u00e0 la pr\u00e9sence de non pas un, mais Richter a tenu son \u00e9v\u00e9nement annuel sur les pr\u00e9visions \u00e9conomiques conjointement avec la Banque\u00a0TD.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/previsions-economiques-pour-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Pr\u00e9visions \u00e9conomiques pour 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/11833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=11833"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=11833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}