{"id":12083,"date":"2020-03-13T23:45:03","date_gmt":"2020-03-13T22:45:03","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=medianews&#038;p=12083"},"modified":"2020-12-16T17:44:23","modified_gmt":"2020-12-16T16:44:23","slug":"covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/","title":{"rendered":"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9"},"content":{"rendered":"<p><em>Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. <\/em><\/p>\n<p>Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos clients, de nos employ\u00e9s et de notre communaut\u00e9 au s\u00e9rieux.<\/p>\n<p>En r\u00e9ponse au COVID-19, nous voulons partager avec vous les mesures que nous prenons en tant que cabinet, pour contribuer \u00e0 limiter la propagation du virus et sa transmission. Nous avons un comit\u00e9 d\u2019intervention en place qui surveille l\u2019\u00e9volution de pr\u00e8s et qui nous avise au fur et \u00e0 mesure.<\/p>\n<p>En ayant \u00e0 c\u0153ur la sant\u00e9 mentale et physique de nos clients, nos membres d\u2019\u00e9quipes, nos invit\u00e9s, nos fournisseurs et notre communaut\u00e9, ainsi qu\u2019en suivant les recommandations faites par notre gouvernement et l\u2019Organisation mondiale de la sant\u00e9, nous voulons partager avec vous <strong>les mesures pr\u00e9ventives que Richter a prises jusqu\u2019\u00e0 pr\u00e9sent :<\/strong><\/p>\n<p>&#8211; Bien que nos bureaux soient toujours ouverts \u00e0 Toronto et \u00e0 Montr\u00e9al, nous encourageons la majorit\u00e9 des membres de notre \u00e9quipe \u00e0 travailler de la maison.<\/p>\n<ul>\n<li>Nous avons d\u00e9j\u00e0 en place une politique de t\u00e9l\u00e9travail, donc notre infrastructure est \u00e9tablie pour que notre \u00e9quipe puisse travailler \u00e0 domicile, pour pouvoir poursuivre le travail comme d\u2019habitude.<\/li>\n<li>Les rencontres virtuelles sont disponibles \u00e0 tous les membres de l\u2019\u00e9quipe Richter, par Skype, vid\u00e9oconf\u00e9rence ou appels t\u00e9l\u00e9phoniques.<\/li>\n<li>Nous avons mis \u00e0 jour nos r\u00e9ponses d\u2019urgences et nos plans de communications pour nous adapter \u00e0 toute situation.<\/li>\n<\/ul>\n<p>&#8211; Nos \u00e9quipes responsables des installations des deux bureaux gardent toujours les espaces propres, mais ont aussi augment\u00e9 la fr\u00e9quence de nettoyage des endroits le plus fr\u00e9quemment utilis\u00e9s, telles que les poign\u00e9es de porte, les tables, les salles de conf\u00e9rence et les machines \u00e0 caf\u00e9. De plus, des nettoyants antiseptiques pour les mains et des serviettes humides nettoyantes sont disponibles.<\/p>\n<p>&#8211; Nous avons annul\u00e9 tous les grands \u00e9v\u00e8nements et activit\u00e9s qui devaient avoir lieu chez Richter pour les 30 prochains jours.<\/p>\n<p>&#8211; Nous limitons tous les d\u00e9placements qui ne sont pas essentiels pour les affaires et nous \u00e9vitons de voyager entre les bureaux de Montr\u00e9al et Toronto pour les 30 prochains jours.<\/p>\n<p><strong>Avant de visiter nos bureaux, nous vous encourageons \u00e0 informer un associ\u00e9\/personne-ressource chez Richter si :<\/strong><\/p>\n<p>&#8211; Vous \u00e9prouvez des sympt\u00f4mes de rhume ou de grippe; si c\u2019est le cas, nous reporterons votre visite \u00e0 un moment plus opportun ou sugg\u00e9rerons d\u2019organiser la rencontre par t\u00e9l\u00e9phone ou vid\u00e9oconf\u00e9rence.<\/p>\n<p>&#8211; Vous avez voyag\u00e9 \u00e0 l\u2019ext\u00e9rieur du Canada r\u00e9cemment, car les recommandations actuelles du gouvernement stipulent que les personnes doivent rester \u00e0 la maison pendant 14 jours d\u2019isolement obligatoire, m\u00eame si elles sont asymptomatiques, \u00e0 leur retour.<\/p>\n<p>Bien que normalement nous nous r\u00e9jouissons de vous accueillir chaleureusement avec une poign\u00e9e de main, pour le moment nous encourageons notre \u00e9quipe et tout le monde \u00e0 suivre les meilleures pratiques : ne vous serez pas la main, lavez-vous les mains fr\u00e9quemment, transportez sur vous un d\u00e9sinfectant pour les mains et limitez autant que possible de vous toucher le visage.<\/p>\n<p>Nous continuerons de surveiller la situation et de nous assurer d\u2019offrir les services \u00e0 la client\u00e8le n\u00e9cessaires et attendus de tous chez Richter. Nous appr\u00e9cions la coop\u00e9ration de chacun au sein de la firme et l\u2019\u00e9quipe de ce comit\u00e9 se fera un plaisir de r\u00e9pondre \u00e0 toutes vos questions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos clients, de nos employ\u00e9s et de notre communaut\u00e9 au s\u00e9rieux. En r\u00e9ponse au COVID-19, nous voulons partager avec vous les mesures que nous prenons en tant que cabinet, pour contribuer \u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1358],"class_list":["post-12083","insights","type-insights","status-publish","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter<\/title>\n<meta name=\"description\" content=\"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter\" \/>\n<meta property=\"og:description\" content=\"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-16T16:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\\\/\",\"name\":\"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2020-03-13T22:45:03+00:00\",\"dateModified\":\"2020-12-16T16:44:23+00:00\",\"description\":\"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter","description":"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter","og_description":"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2020-12-16T16:44:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/","name":"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9 - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2020-03-13T22:45:03+00:00","dateModified":"2020-12-16T16:44:23+00:00","description":"Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19. Richter prend la sant\u00e9 et la s\u00e9curit\u00e9 de nos Chez Richter, nous prenons des mesures sp\u00e9cifiques pour contribuer \u00e0 ralentir la propagation du COVID-19.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-notre-engagement-envers-nos-clients-notre-equipe-et-notre-communaute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"COVID-19 : Notre engagement envers nos clients, notre \u00e9quipe et notre communaut\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/12083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=12083"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=12083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}