{"id":12439,"date":"2020-04-14T16:59:29","date_gmt":"2020-04-14T14:59:29","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=medianews&#038;p=12439"},"modified":"2021-03-05T19:32:46","modified_gmt":"2021-03-05T18:32:46","slug":"covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/","title":{"rendered":"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d&rsquo;urgence du Canada \u2013 5"},"content":{"rendered":"<h2>Subvention salariale d&rsquo;urgence du Canada (\u201cSSUC\u201d) &#8211; R\u00e9sum\u00e9<\/h2>\n<h2><em><span style=\"font-size: 30px;\">Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Vous trouverez ci-dessous un r\u00e9sum\u00e9 du programme ainsi que les choix importants qui devront \u00eatre faits. Veuillez noter que certains aspects du programme sont plus amplement discut\u00e9s dans notre dernier <a href=\"https:\/\/www.richter.ca\/fr\/news-media\/covid-19-bulletin-4-canada-mesures-supplementaires\/\" target=\"_blank\" rel=\"noopener noreferrer\"><u>bulletin dat\u00e9 du 8 avril 2020<\/u><\/a>. Compte tenu de la nature complexe des r\u00e8gles, il est fortement recommand\u00e9 aux lecteurs de communiquer avec leur conseiller de chez Richter afin que leurs impacts soient ad\u00e9quatement interpr\u00e9t\u00e9s.<\/span><\/em><\/h2>\n<p>&nbsp;<\/p>\n<h3>Calcul de la subvention<\/h3>\n<ul>\n<li>Un employeur pourra recevoir une subvention en fonction du salaire pay\u00e9 \u00e0 leurs employ\u00e9s \u00e0 l&rsquo;\u00e9gard de la p\u00e9riode entre le 15 mars 2020 et le 6 juin 2020.<\/li>\n<li>La subvention pourra \u00eatre r\u00e9clam\u00e9e pour les employ\u00e9s \u00e0 temps plein ou \u00e0 temps partiel, dans la mesure o\u00f9 ces derniers sont r\u00e9mun\u00e9r\u00e9s par leur employeur pendant au moins 15 jours cons\u00e9cutifs durant chacune des trois p\u00e9riodes d&rsquo;admissibilit\u00e9 distinctes suivantes (les \u201cP\u00e9riodes d\u2019admissibilit\u00e9\u201d):\n<ul>\n<li>Du 15 mars au 11 avril;<\/li>\n<li>Du 12 avril au 9 mai; et<\/li>\n<li>Du 10 mai au 6 juin.<\/li>\n<\/ul>\n<\/li>\n<li>Le montant de la subvention sera d\u00e9termin\u00e9 selon une formule et bas\u00e9 en fonction de la r\u00e9mun\u00e9ration d\u2019avant et apr\u00e8s la crise; mais dans tous les cas, le montant de la subvention ne pourra pas exc\u00e9der 847 $ par semaine. Pour un employ\u00e9 avec lien de d\u00e9pendance, il y a une condition additionnelle \u00e0 l&rsquo;effet que ce dernier devait \u00eatre \u00e0 l\u2019emploi entre le 1er janvier 2020 et le 15 mars 2020.<\/li>\n<li>Pour un employ\u00e9 qui est en cong\u00e9 pay\u00e9, un employeur pourra aussi recevoir un remboursement de 100% des cotisations employeur \u00e0 l\u2019assurance-emploi, au R\u00e9gime de pensions du Canada, au R\u00e9gime de rentes du Qu\u00e9bec et au R\u00e9gime qu\u00e9b\u00e9cois d\u2019assurance parentale.<\/li>\n<li>Le site web de Finance Canada mentionne qu\u2019il est attendu que les employeurs fassent de leur mieux pour que les employ\u00e9s touchent leur salaire d&rsquo;avant la crise.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Conditions d&rsquo;admissibilit\u00e9<\/h3>\n<ul>\n<li>Toutes les entreprises, les organismes sans but lucratif et les organismes de bienfaisance enregistr\u00e9s, peu importe leur taille, pourront r\u00e9clamer la SSUC.<\/li>\n<li>Une entreprise doit avoir subi une baisse de revenus durant le mois de mars (15%), avril (30%) et mai (30%). Les employeurs pourront utiliser un des deux points de rep\u00e8re indiqu\u00e9s ci-dessous afin de d\u00e9terminer leur baisse de revenus.\n<ul>\n<li>Les revenus mensuels gagn\u00e9s en 2020, compar\u00e9s au m\u00eame mois en 2019; ou<\/li>\n<li>La moyenne des revenus gagn\u00e9s en janvier et f\u00e9vrier 2020, compar\u00e9s au mois pour lequel la SSUC est r\u00e9clam\u00e9e.<\/li>\n<\/ul>\n<\/li>\n<li>Le point de rep\u00e8re choisi doit \u00eatre utilis\u00e9 pendant toute la dur\u00e9e du programme.<\/li>\n<li>Si l&#8217;employeur n&rsquo;exploitait pas d&rsquo;entreprise au 1er mars 2019, le point de rep\u00e8re sera automatiquement la moyenne des revenus gagn\u00e9s en janvier et f\u00e9vrier 2020.<\/li>\n<li>Si un employeur satisfait le test de baisse de revenus pour une P\u00e9riode d&rsquo;admissibilit\u00e9, il sera r\u00e9put\u00e9 avoir satisfait ce test pour la prochaine p\u00e9riode aussi. Par exemple, si un employeur satisfait le test de baisse de revenus pour le mois de mars, il pourra r\u00e9clamer la SSUC pour la premi\u00e8re et la deuxi\u00e8me P\u00e9riode d&rsquo;admissibilit\u00e9.<\/li>\n<li>La personne ayant la responsabilit\u00e9 principale des activit\u00e9s financi\u00e8res de l\u2019employeur doit attester que la demande pour la SSUC est compl\u00e8te et exacte quant \u00e0 tous les \u00e9l\u00e9ments importants. De fa\u00e7on g\u00e9n\u00e9rale, cette personne sera un cadre dirigeant dans l&rsquo;entreprise.<\/li>\n<li>L&#8217;employeur doit avoir un num\u00e9ro d&rsquo;entreprise enregistr\u00e9 pour un compte de retenu sur la paie en date du 15 mars 2020.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Calcul des revenus et d\u00e9termination de la baisse des revenus<\/h3>\n<ul>\n<li>Les revenus peuvent \u00eatre calcul\u00e9s selon la m\u00e9thode de la comptabilit\u00e9 d&rsquo;exercice ou, si un employeur fait le choix, selon la m\u00e9thode de la comptabilit\u00e9 de caisse.<\/li>\n<li>La m\u00e9thode de comptabilit\u00e9 choisie doit \u00eatre utilis\u00e9e pendant toute la dur\u00e9e du programme.<\/li>\n<li>De fa\u00e7on g\u00e9n\u00e9rale, il faut inclure dans les revenus les rentr\u00e9es de sommes d\u2019argent et autres contreparties re\u00e7ues ou \u00e0 recevoir dans le cours des activit\u00e9s normales de l&#8217;employeur, mais excluant les postes extraordinaires ainsi que des montants provenant de personnes avec qui l\u2019employeur a un lien de d\u00e9pendance.<\/li>\n<li>Pour les organismes sans but lucratif, il faut inclure dans les revenus les frais \u00e0 titre de cotisation (droit d\u2019inscription ou autre), et, pour les organismes de bienfaisance enregistr\u00e9s, les dons. Ces entit\u00e9s pourront choisir d&rsquo;inclure ou d&rsquo;exclure les revenus provenant de sources gouvernementales.<\/li>\n<li>Les revenus de chaque membre d\u2019un \u201cgroupe affili\u00e9\u201d pourront \u00eatre calcul\u00e9s sur une base consolid\u00e9e, si tous les membres du groupe font un choix conjoint \u00e0 cet effet. Veuillez noter que la notion de \u201cgroupe affili\u00e9\u201d est bas\u00e9e sur des r\u00e8gles fiscales complexes.<\/li>\n<li>Un employeur qui re\u00e7oit la totalit\u00e9 ou presque de ses revenus d&rsquo;une ou de plusieurs entit\u00e9s avec qui il a un lien de d\u00e9pendance pourra r\u00e9clamer la SSUC si certaines conditions sont remplies et si l&#8217;employer fait un choix conjoint avec chacune des entit\u00e9s.<\/li>\n<li>Des r\u00e8gles particuli\u00e8res s&rsquo;appliquent pour les groupes corporatifs qui pr\u00e9parent normalement des \u00e9tats financiers consolid\u00e9s ainsi que pour les coentreprises.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Processus d&rsquo;application<\/h3>\n<ul>\n<li>Un employeur pourra demander la subvention via le portail <em>Mon dossier d\u2019entreprise <\/em>de l\u2019Agence du revenu du Canada (\u201cARC\u201d) ou via une demande en ligne.<\/li>\n<li>L&#8217;employeur aura jusqu\u2019au 30 septembre 2020 afin de r\u00e9clamer la SSUC.<\/li>\n<li>Les demandes pourront \u00eatre effectu\u00e9es dans les prochaines 2 \u00e0 4 semaines et l\u2019ARC commencera \u00e0 d\u00e9bourser les montants dans environ 4 semaines. Consid\u00e9rant le d\u00e9lai entre le paiement des salaires aux employ\u00e9s et la r\u00e9ception de la SSUC, les employeurs devront financer les paies temporairement.<\/li>\n<li>Si un employeur n&rsquo;est pas encore enregistr\u00e9 \u00e0 <em>Mon dossier d\u2019entreprise <\/em>de l\u2019ARC, nous vous encourageons \u00e0 le faire d\u00e8s que possible.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>R\u00e8gle anti-\u00e9vitement<\/h3>\n<ul>\n<li>Si les revenus sont r\u00e9duits dans le but de r\u00e9clamer la SSUC, une r\u00e8gle anti-\u00e9vitement de port\u00e9e tr\u00e8s large pourrait s&rsquo;appliquer, imposant un remboursement de tout montant re\u00e7u en vertu de la SSUC ainsi qu\u2019une p\u00e9nalit\u00e9 additionnelle de 25%.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<h3>SSUC \u2013 Les choix IMPORTANTS pour un employeur<\/h3>\n<ul>\n<li><strong>Choix d\u2019un point de rep\u00e8re:<\/strong> Un employeur devra choisir le meilleur point de rep\u00e8re afin de d\u00e9terminer leur baisse de revenus, selon les revenus d&rsquo;un mois en 2020 compar\u00e9s au m\u00eame mois en 2019 ou la moyenne de janvier et de f\u00e9vrier 2020.<\/li>\n<li><strong>Choix d&rsquo;une m\u00e9thode de comptabilit\u00e9: <\/strong>Un employeur devra choisir la meilleure m\u00e9thode afin de d\u00e9terminer leur baisse de revenus, soit selon la m\u00e9thode de la comptabilit\u00e9 d&rsquo;exercice ou la m\u00e9thode de la comptabilit\u00e9 de caisse.<\/li>\n<li><strong>Choix de calculer les revenus d\u2019un \u201cgroupe affili<\/strong><strong>\u00e9<\/strong><strong>\u201d sur une base consolid\u00e9e<\/strong>: Les membres d\u2019un \u201cgroupe affili\u00e9\u201d devront d\u00e9cider s\u2019ils produisent leurs demandes de SSUC sur la base de revenus consolid\u00e9s ou non. Si un calcul des revenus sur une base consolid\u00e9e est choisi, tous les membres du groupe doivent faire un choix conjoint \u00e0 cet effet.<\/li>\n<li><strong>Choix pour les entit\u00e9s ayant un lien de d\u00e9pendance<\/strong>: Si un employeur re\u00e7oit la totalit\u00e9 ou presque de ses revenus d\u2019une ou de plusieurs entit\u00e9s avec qui il a un lien de d\u00e9pendance, il pourrait \u00eatre \u00e9ligible \u00e0 r\u00e9clamer la SSUC bas\u00e9e sur la baisse de revenus de ces entit\u00e9s dans la mesure o\u00f9 il fait un choix conjoint avec chacune de ces entit\u00e9s.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Autres<\/h3>\n<ul>\n<li>La Prestation canadienne d\u2019urgence (\u201cPCU\u201d) (2 000$\/mois) ne peut pas \u00eatre r\u00e9clam\u00e9e en m\u00eame temps que la SSUC \u00e0 l\u2019\u00e9gard d\u2019un m\u00eame employ\u00e9. Par cons\u00e9quent, le gouvernement f\u00e9d\u00e9ral a mentionn\u00e9 qu&rsquo;il consid\u00e9rera un processus de v\u00e9rification afin d&rsquo;\u00e9viter la duplication des demandes, telqu\u2019un processus selon lequel l&#8217;employ\u00e9 pourra annuler sa demande et rembourser les montants re\u00e7us de la PCU. Nous vous communiquerons les d\u00e9tails concernant le processus de v\u00e9rification lorsqu&rsquo;ils seront disponibles.<\/li>\n<li>\u00c9tant donn\u00e9 que la SSUC est un programme qui d\u00e9montre un haut niveau de confiance \u00e0 l&rsquo;\u00e9gard des demandeurs ainsi que des p\u00e9nalit\u00e9s importantes en cas de non-conformit\u00e9, il est fortement recommand\u00e9 que l&#8217;employeur maintienne un registre afin de documenter la baisse des revenus, les salaires pay\u00e9s aux employ\u00e9s ainsi que son processus de d\u00e9cision supportant ses demandes.<\/li>\n<li>Le nom d\u2019un employeur qui fait une demande pour obtenir la SSUC pourra \u00eatre rendu public par l\u2019ARC. Il n&rsquo;est pas clair pourquoi ceci a \u00e9t\u00e9 ajout\u00e9 dans la loi.<\/li>\n<li>Les r\u00e9clamations selon la Subvention salariale temporaire (la subvention de 10%) ainsi que les prestations d\u2019assurance emploi re\u00e7ues par les employ\u00e9s selon un programme de Travail partag\u00e9 r\u00e9duiront le montant de la prestation que l&#8217;employeur pourra recevoir en vertu de la SSUC.<\/li>\n<li>Tout montant re\u00e7u par un employeur en vertu de la SSUC sera inclus dans son revenu imposable et r\u00e9duira le montant de r\u00e9mun\u00e9ration admissible aux fins de certains cr\u00e9dits d&rsquo;imp\u00f4t (par exemple, RS&amp;DE).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/04\/richter_mise-a-jour_subvention-salariale-durgence-du-canada_5-2020-04-14.pdf\" target=\"_blank\" rel=\"attachment noopener wp-att-12441 noreferrer\">VERSION IMPRIMABLE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Subvention salariale d&rsquo;urgence du Canada (\u201cSSUC\u201d) &#8211; R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Vous trouverez ci-dessous un r\u00e9sum\u00e9 du programme ainsi que les choix importants qui devront \u00eatre faits. Veuillez noter que certains aspects du programme sont plus amplement discut\u00e9s dans notre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1358],"class_list":["post-12439","insights","type-insights","status-publish","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d&#039;urgence du Canada \u2013 5 - Richter<\/title>\n<meta name=\"description\" content=\"Subvention salariale d&#039;urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d&#039;urgence du Canada \u2013 5 - Richter\" \/>\n<meta property=\"og:description\" content=\"Subvention salariale d&#039;urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T18:32:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\\\/\",\"name\":\"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d'urgence du Canada \u2013 5 - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2020-04-14T14:59:29+00:00\",\"dateModified\":\"2021-03-05T18:32:46+00:00\",\"description\":\"Subvention salariale d'urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d&rsquo;urgence du Canada \u2013 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d'urgence du Canada \u2013 5 - Richter","description":"Subvention salariale d'urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d'urgence du Canada \u2013 5 - Richter","og_description":"Subvention salariale d'urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-03-05T18:32:46+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/","name":"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d'urgence du Canada \u2013 5 - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2020-04-14T14:59:29+00:00","dateModified":"2021-03-05T18:32:46+00:00","description":"Subvention salariale d'urgence du Canada (\u201cSSUC\u201d) - R\u00e9sum\u00e9 Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral. Le 11 avril 2020, la loi mettant en vigueur la SSUC a \u00e9t\u00e9 adopt\u00e9e par le gouvernement f\u00e9d\u00e9ral.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/covid-19-canada-mise-a-jour-subvention-salariale-durgence-du-canada-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"COVID-19 : Canada, Mise \u00e0 jour : Subvention salariale d&rsquo;urgence du Canada \u2013 5"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/12439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=12439"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=12439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}