{"id":12701,"date":"2020-05-15T18:47:23","date_gmt":"2020-05-15T16:47:23","guid":{"rendered":"https:\/\/www.richter.ca\/?p=12701"},"modified":"2021-07-23T15:47:37","modified_gmt":"2021-07-23T13:47:37","slug":"serie-lheure-de-verite-pas-toujours-evident-detre-equitable","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/","title":{"rendered":"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable"},"content":{"rendered":"<h2 style=\"font-size: 30px;\">Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute leur vie pour b\u00e2tir une entreprise \u00e0 l\u2019image de leurs aspirations, ne font pas exception.<\/h2>\n<p>Maintenant que vous devez commencer \u00e0 planifier votre d\u00e9part et peut-\u00eatre le transfert de votre entreprise, vous pourriez avoir des choix difficiles \u00e0 faire. Devriez-vous confier \u00e0 chacun de vos enfants une part \u00e9gale dans l\u2019entreprise? Ou devriez-vous plut\u00f4t les \u00e9valuer individuellement en tenant compte de leurs atouts, en reconnaissant qu\u2019ils n\u2019ont pas n\u00e9cessairement la bosse des affaires?<\/p>\n<p>Ce n\u2019est pas simple de pr\u00e9dire l\u2019avenir de son entreprise, surtout quand les \u00e9motions entrent en jeu. Nos associ\u00e9s, qui misent sur une planification rigoureuse et une grande ouverture d\u2019esprit, ont aid\u00e9 des milliers de propri\u00e9taires d\u2019entreprises \u00e0 traverser cette p\u00e9riode, et ce, dans toutes sortes de circonstances.<\/p>\n<h3><strong>Le d\u00e9fi<\/strong><\/h3>\n<p>Jordan Gould, associ\u00e9 chez Richter, entretient une relation d\u2019affaires avec le client en question depuis le milieu des ann\u00e9es 1990. Le client a proc\u00e9d\u00e9 \u00e0 un gel successoral pour que ses deux\u00a0enfants int\u00e8grent l\u2019entreprise (un seul d\u2019entre eux a \u00e9tudi\u00e9 dans le domaine des affaires). Il s\u2019agit donc d\u2019un enjeu fr\u00e9quent pour bien des familles\u00a0: <strong>l\u2019\u00e9quit\u00e9. <\/strong><\/p>\n<p>Si l\u2019un des enfants montre un int\u00e9r\u00eat et la volont\u00e9 n\u00e9cessaire pour prendre les r\u00eanes de l\u2019entreprise alors que l\u2019autre n\u2019a pas le sens des affaires, n\u2019a pas \u00e9tudi\u00e9 dans ce domaine ou ne se montre pas int\u00e9ress\u00e9, comment r\u00e9ussir la transmission \u00e0 la prochaine g\u00e9n\u00e9ration le temps venu? Dans le cas d\u2019une transition, <strong>comment le propri\u00e9taire de l\u2019entreprise peut-il \u00e9viter de cr\u00e9er des rivalit\u00e9s entre ses enfants?<\/strong><\/p>\n<p><a href=\"https:\/\/www.richter.ca\/fr\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/shutterstock_290613629-2\/\" rel=\"attachment wp-att-12768\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12768 size-large\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg\" alt=\"3 g\u00e9n\u00e9rations d'une m\u00eame famille assis au bord de l'eau\" width=\"1024\" height=\"683\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg 1024w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-600x400.jpg 600w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-768x512.jpg 768w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1536x1024.jpg 1536w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<h3><strong>La solution<\/strong><\/h3>\n<p>Cette d\u00e9cision n\u2019a vraiment pas \u00e9t\u00e9 facile pour le client. Apr\u00e8s plusieurs rencontres avec le propri\u00e9taire et son conseiller juridique, ainsi qu\u2019\u00e0 la suite de plusieurs t\u00eate-\u00e0-t\u00eate, Jordan a pu sugg\u00e9rer des options novatrices pour diviser le patrimoine de fa\u00e7on \u00e9quitable, tout en r\u00e9glant la question de l\u2019attribution de l\u2019entreprise. Apr\u00e8s avoir pris en consid\u00e9ration ses options, le client et sa conjointe ont d\u00e9cid\u00e9 de confier une participation de 80\u00a0% de l\u2019entreprise \u00e0 l\u2019enfant qui s\u2019y investissait le plus. Pour s\u2019assurer que son autre enfant obtienne une valeur \u00e9gale, le client lui a confi\u00e9 des actifs du patrimoine qui n\u2019\u00e9taient pas li\u00e9s \u00e0 l\u2019entreprise. Cependant, ce processus a d\u00e9stabilis\u00e9 la dynamique familiale. La famille s\u2019en est sortie \u00e0 force de discuter ouvertement et en toute franchise, accompagn\u00e9e de Jordan et de leur conseiller juridique.<\/p>\n<h3><strong>L\u2019avantage <\/strong><\/h3>\n<p>Une structure de primes a aussi \u00e9t\u00e9 instaur\u00e9e pour le p\u00e8re \u00e0 la suite de la transition de l\u2019entreprise pour veiller \u00e0 ce qu\u2019il continue de toucher une r\u00e9mun\u00e9ration importante, et ce, malgr\u00e9 le gel de sa participation dans l\u2019entreprise. De plus, ce gel lui a permis de verser une r\u00e9mun\u00e9ration \u00e0 ses enfants pour leur contribution respective \u00e9ventuelle \u00e0 la croissance de l\u2019entreprise.<\/p>\n<p>Depuis ce moment-l\u00e0, l\u2019entreprise a connu un essor et a d\u00e9cupl\u00e9 sa croissance. Le p\u00e8re est malheureusement d\u00e9c\u00e9d\u00e9 il y a quelques ann\u00e9es. Mais la transition avait \u00e9t\u00e9 bien planifi\u00e9e. La famille entretient toujours des liens harmonieux et les membres se soutiennent, m\u00eame dans les moments difficiles.<\/p>\n<h3><strong>Aper\u00e7u de l\u2019entreprise aujourd\u2019hui<\/strong><\/h3>\n<p>\u00c0 l\u2019heure actuelle, le premier enfant d\u00e9tient toujours une participation de 80\u00a0% dans l\u2019entreprise et s\u2019accomplit dans son r\u00f4le de pr\u00e9sident et de chef de la direction. Le deuxi\u00e8me enfant a quant \u00e0 lui pris sa retraite. Leurs enfants, donc la troisi\u00e8me g\u00e9n\u00e9ration, sont dans la vingtaine. Ils ne s\u2019investissent pas dans l\u2019entreprise encore, et peut-\u00eatre qu\u2019ils ne s\u2019y investiront jamais, ce qui soul\u00e8ve la question suivante\u00a0: \u00ab\u00a0Quels sont les objectifs de la g\u00e9n\u00e9ration plus jeune?\u00a0\u00bb Les propri\u00e9taires de l\u2019entreprise devront se pencher sur cette question, car l\u2019avenir de l\u2019entreprise en d\u00e9pend et des offres d\u2019achat commencent \u00e0 se pr\u00e9senter\u2026<\/p>\n<h3><strong>Services fournis<\/strong><\/h3>\n<p>Nous avons mis sur pied un plan successoral pour assurer la p\u00e9rennit\u00e9 de l\u2019entreprise pour la deuxi\u00e8me g\u00e9n\u00e9ration, ce qui comprenait une \u00e9valuation de l\u2019entreprise et un gel successoral. Pendant pr\u00e8s de trente\u00a0ans, l\u2019associ\u00e9 Jordan\u00a0Gould a donn\u00e9 des conseils \u00e0 la famille, en lui proposant une proc\u00e9dure pour g\u00e9rer la situation, sans toutefois imposer quoi que ce soit. Les membres de la famille indiquent qu\u2019ils peuvent toujours compter sur Jordan pour leur fournir des commentaires objectifs et une analyse logique. Ils peuvent ainsi trouver leurs propres solutions et s\u2019orienter dans une voie qui leur convient d\u2019un commun accord.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute leur vie pour b\u00e2tir une entreprise \u00e0 l\u2019image de leurs aspirations, ne font pas exception. Maintenant que vous devez commencer \u00e0 planifier votre d\u00e9part et peut-\u00eatre le transfert de votre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1356],"class_list":["post-12701","insights","type-insights","status-publish","hentry","insights-type-planification-de-la-transition-et-de-la-succession"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter<\/title>\n<meta name=\"description\" content=\"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter\" \/>\n<meta property=\"og:description\" content=\"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T13:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/\",\"name\":\"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/shutterstock_290613629-1024x683.jpg\",\"datePublished\":\"2020-05-15T16:47:23+00:00\",\"dateModified\":\"2021-07-23T13:47:37+00:00\",\"description\":\"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/shutterstock_290613629-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/shutterstock_290613629-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter","description":"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter","og_description":"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-07-23T13:47:37+00:00","og_image":[{"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/","name":"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg","datePublished":"2020-05-15T16:47:23+00:00","dateModified":"2021-07-23T13:47:37+00:00","description":"Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement. Et les entrepreneurs, qui ont travaill\u00e9 fort toute Tout parent aime chacun de ses enfants et fait de son mieux pour toujours les traiter \u00e9quitablement.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/#primaryimage","url":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg","contentUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/05\/shutterstock_290613629-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/serie-lheure-de-verite-pas-toujours-evident-detre-equitable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"S\u00e9rie\u00a0: L\u2019heure de v\u00e9rit\u00e9\u00a0: Pas toujours \u00e9vident d\u2019\u00eatre \u00e9quitable"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/12701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=12701"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=12701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}