{"id":12852,"date":"2020-06-04T19:31:07","date_gmt":"2020-06-04T17:31:07","guid":{"rendered":"https:\/\/www.richter.ca\/?p=12852"},"modified":"2021-07-23T15:41:25","modified_gmt":"2021-07-23T13:41:25","slug":"conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/","title":{"rendered":"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille  gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions"},"content":{"rendered":"<h2 style=\"font-size: 30px;\">Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.<\/h2>\n<p>Ils ont besoin d\u2019un conseiller de confiance \u00e0 qui ils peuvent parler, en toute qui\u00e9tude, de leurs pr\u00e9occupations ou des conflits concernant des membres de la famille. On peut penser qu\u2019il s\u2019agit de r\u00e9solution de conflits, mais, \u00e0 l\u2019occasion, certaines personnes ne savent pas qu\u2019elles vivent une situation bien r\u00e9elle de conflit, car elles ne communiquent tout simplement pas. La cl\u00e9, c\u2019est vraiment de cr\u00e9er des liens.<\/p>\n<p>En 2016, Campden Wealth et Morgan Stanley Private Wealth Management ont publi\u00e9 une \u00e9tude men\u00e9e aupr\u00e8s de particuliers tr\u00e8s bien nantis pour conna\u00eetre leur point de vue sur le processus d\u00e9cisionnel au sein de leur famille. Voici un r\u00e9sum\u00e9 des conclusions qu\u2019elles en ont tir\u00e9es : \u00ab Sur une note encourageante, et contrairement \u00e0 certaines croyances, notre \u00e9tude a r\u00e9v\u00e9l\u00e9 que la prise de d\u00e9cisions s\u2019av\u00e8re \u00eatre un moteur d\u2019am\u00e9lioration des relations entre les membres de la famille. \u00bb Les auteurs ont constat\u00e9 que les r\u00e9sultats \u00e9taient \u00ab tr\u00e8s certainement attribuables \u00bb \u00e0 la pr\u00e9sence de <a href=\"https:\/\/www.richter.ca\/fr\/solutions\/dynamique-familiale\/\" target=\"_blank\" rel=\"noopener noreferrer\">structures de gouvernance<\/a> et de prise de d\u00e9cisions qui permettent de simplifier le processus d\u00e9cisionnel et de r\u00e9duire les conflits.<\/p>\n<p><a href=\"https:\/\/www.richter.ca\/fr\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/conseils-de-famille\/\" rel=\"attachment wp-att-12853\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12853 size-full\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg\" alt=\"R\u00e9percussion de la prise de d\u00e9cisions li\u00e9es au patrimoine sur les relations entre les membres de la famille; 22% tr\u00e8s positives; 22% plut\u00f4t positives; 30% l\u00e9g\u00e8rement positives; 16% plut\u00f4t n\u00e9gatives; 3% tr\u00e8s n\u00e9gatives; 8% je pr\u00e9f\u00e8re ne pas r\u00e9pondre\" width=\"920\" height=\"776\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg 920w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/06\/conseils-de-famille-600x506.jpg 600w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/06\/conseils-de-famille-768x648.jpg 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h3><span style=\"font-size: 30px;\">\u00ab\u00a0Beaucoup de gens recherchent la simplicit\u00e9, ils souhaitent qu\u2019une personne d\u00e9fende leurs int\u00e9r\u00eats, les prot\u00e8ge et les aide \u00e0 maximiser leurs chances d\u2019atteindre certains objectifs \u2013 \u00e0 la fois financiers et \u00e9motifs. C\u2019est exactement ce que nous faisons chez Richter.\u00a0\u00bb<\/span><\/h3>\n<p><strong><em>\u2013\u00a0<a href=\"https:\/\/www.richter.ca\/fr\/experts\/greg-moore\/\" target=\"_blank\" rel=\"noopener noreferrer\">Greg\u00a0Moore<\/a><\/em><\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h3>CONSEILS DE FAMILLE\u00a0: UNE TRIBUNE POUR LA PRISE DE D\u00c9CISIONS ET LA TENUE DE DISCUSSIONS<\/h3>\n<p>C\u2019est in\u00e9vitable\u00a0: t\u00f4t ou tard, chaque famille vit des conflits entre ses membres. Peu importe la raison ayant men\u00e9 au conflit \u2013 manque de confiance ou de transparence, incompr\u00e9hension d\u2019une situation ou amertume \u2013 ce qui compte le plus, c\u2019est la fa\u00e7on dont le conflit est r\u00e9solu.<\/p>\n<p>Certaines familles b\u00e9n\u00e9ficient pleinement des canaux ad\u00e9quats de communication pour aborder des enjeux urgents, tout particuli\u00e8rement lorsque ceux-ci suscitent des divergences d\u2019opinions. Malheureusement, un conflit non r\u00e9gl\u00e9 peut se pr\u00e9parer tout en \u00e9chappant aux radars pendant des ann\u00e9es avant de refaire surface lorsque la cellule familiale est r\u00e9ellement menac\u00e9e, alors que la famille doit absolument demeurer unie. Il est donc important de tenir un conseil de famille avec des r\u00e8gles bien d\u00e9finies pour que les membres de la famille puissent se r\u00e9unir et avoir des conversations enrichissantes en toute qui\u00e9tude. Le conseil de famille permet \u00e9galement de d\u00e9battre des enjeux et d\u2019en discuter dans un environnement relativement calme. En plus d\u2019\u00e9tablir un climat de confiance et d\u2019unit\u00e9 entre les membres de la famille, les conseils de famille permettent de veiller \u00e0 ce que chacun des membres ait une voix et puisse communiquer ses id\u00e9es.<\/p>\n<p>Les conseils de famille favorisent ainsi la communication ouverte. En mettant tous les participants sur un m\u00eame pied d\u2019\u00e9galit\u00e9, ceux-ci gagnent en confiance.<\/p>\n<h3>CONSTITUTION D\u2019UN CONSEIL DE FAMILLE<\/h3>\n<p>Lors de la constitution d\u2019un conseil de famille, nous encourageons les membres de la famille \u00e0 amener une r\u00e9flexion constructive pour mieux r\u00e9pondre aux besoins de la famille et pour que les conseils soient fructueux pour tous\u00a0:<\/p>\n<ul>\n<li>adopter des politiques officielles quant au d\u00e9roulement des conseils de famille (p. ex., lieu, date et heure, administration);<\/li>\n<li>\u00e9laborer des politiques pour favoriser la participation \u00e0 grande \u00e9chelle;<\/li>\n<li>d\u00e9terminer des r\u00e8gles ou des directives pour la gestion des conflits et la prise de d\u00e9cisions;<\/li>\n<li>officialiser les valeurs et les principes fondamentaux de la famille\u00a0: ils devraient orienter le processus d\u00e9cisionnel et \u00eatre respect\u00e9s par tous les membres de la famille, aussi bien au sein m\u00eame du conseil qu\u2019\u00e0 l\u2019ext\u00e9rieur;<\/li>\n<li>inviter et inciter tous les membres de la famille \u00e0 prendre part \u00e0 la constitution du conseil afin de les mobiliser d\u00e8s le d\u00e9part;<\/li>\n<li>obtenir un consensus lors de discussions;<\/li>\n<li>pratiquer l\u2019\u00e9coute active, porter attention aux autres et respecter les opinions divergentes;<\/li>\n<li>veiller \u00e0 int\u00e9grer des activit\u00e9s familiales et agr\u00e9ables \u2013 les conseils de famille servent \u00e0 tisser des liens et doivent se d\u00e9rouler dans le plaisir.<\/li>\n<\/ul>\n<p>Les conflits ne se r\u00e8glent pas toujours enti\u00e8rement dans le cadre des rencontres des conseils de famille, mais ceux-ci permettent d\u2019\u00e9tablir de bonnes pratiques en mati\u00e8re de communication et de gagner la confiance des membres de la famille, en leur offrant une tribune pour qu\u2019ils se sentent investis et \u00e9cout\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<h3>Consultez \u00e9galement les articles suivants :<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/goals\/moi-et-un-membre-de-ma-famille-sommes-en-conflit-comment-pouvons-nous-regler-la-situation-dans-lharmonie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Moi et un membre de ma famille sommes en conflit. Comment pouvons-nous r\u00e9gler la situation dans l\u2019harmonie?<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/cest-inevitable-alors-pourquoi-tenez-vous-vos-enfants-a-lecart\/\" target=\"_blank\" rel=\"noopener noreferrer\">C\u2019est in\u00e9vitable, alors pourquoi tenez-vous vos enfants \u00e0 l\u2019\u00e9cart?<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/planification-de-la-releve-comment-la-generation-du-millenaire-peut-se-preparer-a-prendre-les-renes-de-lentreprise-familiale\/\" target=\"_blank\" rel=\"noopener noreferrer\">Planification de la rel\u00e8ve. Comment la g\u00e9n\u00e9ration du mill\u00e9naire peut se pr\u00e9parer \u00e0 prendre les r\u00eanes de l\u2019entreprise familiale.<\/a><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive. Ils ont besoin d\u2019un conseiller de confiance \u00e0 qui ils peuvent parler, en toute qui\u00e9tude, de leurs pr\u00e9occupations ou des conflits concernant des membres de la famille. On peut [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1360],"class_list":["post-12852","insights","type-insights","status-publish","hentry","insights-type-gerer-votre-patrimoine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter<\/title>\n<meta name=\"description\" content=\"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter\" \/>\n<meta property=\"og:description\" content=\"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T13:41:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/\",\"name\":\"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/conseils-de-famille.jpg\",\"datePublished\":\"2020-06-04T17:31:07+00:00\",\"dateModified\":\"2021-07-23T13:41:25+00:00\",\"description\":\"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/conseils-de-famille.jpg\",\"contentUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/conseils-de-famille.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter","description":"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter","og_description":"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-07-23T13:41:25+00:00","og_image":[{"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/","name":"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/#primaryimage"},"thumbnailUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg","datePublished":"2020-06-04T17:31:07+00:00","dateModified":"2021-07-23T13:41:25+00:00","description":"Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge Parfois, les membres d\u2019une famille ont besoin d\u2019une personne qui les aidera \u00e0 composer avec une situation difficile \u00e0 r\u00e9gler en raison de la charge \u00e9motive.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/#primaryimage","url":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg","contentUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2020\/06\/conseils-de-famille.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/conseils-de-famille-creer-des-liens-entre-les-membres-de-la-famille-grace-a-de-meilleures-communications-et-prises-de-decisions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Conseils de famille : Cr\u00e9er des liens entre les membres de la famille gr\u00e2ce \u00e0 de meilleures communications et prises de d\u00e9cisions"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/12852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=12852"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=12852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}