{"id":13068,"date":"2020-06-24T22:56:42","date_gmt":"2020-06-24T20:56:42","guid":{"rendered":"https:\/\/www.richter.ca\/?p=13068"},"modified":"2021-07-21T21:12:01","modified_gmt":"2021-07-21T19:12:01","slug":"optimiser-les-portefeuilles-et-repenser-le-risque","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/","title":{"rendered":"Optimiser les portefeuilles et repenser le risque"},"content":{"rendered":"<h2 style=\"font-size: 30px;\">Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses. Votre fa\u00e7on de voir les choses peut changer rapidement selon que vous, votre entreprise et votre famille vous trouviez au sommet ou au creux de la vague. Pour affronter les temp\u00eates \u00e9conomiques, mieux vaut \u00eatre \u00e0 bord d\u2019une embarcation stable sous la gouverne d\u2019un capitaine fiable, qui gardera votre portefeuille sur la bonne voie et qui tiendra le cap vers vos objectifs.<\/h2>\n<p>Comment une famille peut-elle tirer le maximum de son portefeuille et g\u00e9rer le risque en cette p\u00e9riode de turbulences? Karen\u00a0Sankhi et Richard\u00a0Leon, deux directeurs, Relation avec les clients et professionnels chevronn\u00e9s du Bureau familial Richter\u00a0(BFR), partagent leur point de vue sur les mesures \u00e0 prendre pour non seulement garder le cap en p\u00e9riode d\u2019instabilit\u00e9, mais aussi d\u00e9couvrir les occasions cach\u00e9es.<\/p>\n<p><strong>Nous traversons une p\u00e9riode hors du commun qui semble \u00eatre la plus grande crise de notre vie. Que devrions-nous garder \u00e0 l\u2019esprit lorsque nous g\u00e9rons des portefeuilles en p\u00e9riode d\u2019instabilit\u00e9 \u00e9conomique?<\/strong><\/p>\n<p><strong>Richard\u00a0Leon (RL)\u00a0:<\/strong> Nous traversons bel et bien une crise incroyable. Et m\u00eame si toutes les crises ne se ressemblent pas, il n\u2019est pas faux de dire qu\u2019elles suscitent g\u00e9n\u00e9ralement les m\u00eames r\u00e9actions. La premi\u00e8re \u00e0 se manifester est habituellement la panique, car le chaos est souvent une grande source de stress. Or, m\u00eame si le stress est une r\u00e9action tout \u00e0 fait normale, il ne doit pas dicter vos d\u00e9cisions financi\u00e8res. Il y aura toujours des crises. Cependant, adopter d\u2019entr\u00e9e de jeu une approche structur\u00e9e pour votre portefeuille peut vous aider \u00e0 obtenir le meilleur rendement possible \u00e0 long terme, m\u00eame en p\u00e9riode d\u2019incertitude. Il y a trois choses \u00e0 garder en t\u00eate en p\u00e9riode d\u2019instabilit\u00e9 \u00e9conomique g\u00e9n\u00e9ralis\u00e9e\u00a0: la planification financi\u00e8re, la diversification ad\u00e9quate du portefeuille et la recherche d\u2019occasions. Au BFR, nous recommandons \u00e0 nos clients de toujours tenir compte de la diversification de leur portefeuille, en particulier dans les cat\u00e9gories d\u2019actif qui sont moins sensibles \u00e0 la croissance \u00e9conomique. Nous sommes ainsi en mesure de choisir des fonds potentiellement plus prudents qui pourront offrir un revenu et g\u00e9n\u00e9rer de la croissance dans des conjonctures o\u00f9 les fonds plus sensibles, comme les fonds d\u2019actions, sont vuln\u00e9rables. La crise actuelle s\u2019est fait ressentir rapidement et durement sur certains secteurs, ce qui peut avoir un impact sur les placements. Lorsque nous \u00e9valuons les portefeuilles de nos clients, nous essayons d\u2019y rep\u00e9rer les faiblesses et de trouver une mani\u00e8re d\u2019y rem\u00e9dier. Mais nous tentons \u00e9galement de trouver des occasions et d\u2019en tirer parti. Peu de gens associent instabilit\u00e9 \u00e9conomique et occasions de placement. Or, il existe de nombreuses fa\u00e7ons de miser sur l\u2019\u00e9tat actuel du march\u00e9 pour obtenir des rendements. Lors de crises comme celle que nous traversons, nous analysons le profil des gestionnaires qui tirent leur \u00e9pingle du jeu et nous cherchons m\u00eame de nouveaux gestionnaires qui sortent du lot.<\/p>\n<h3 style=\"padding-left: 40px;\"><span style=\"font-size: 30px;\">Le stress est une r\u00e9action tout \u00e0 fait normale, mais il ne doit pas dicter vos d\u00e9cisions financi\u00e8res.<\/span><\/h3>\n<p><strong>Karen\u00a0Sankhi (KS)\u00a0:<\/strong> Je suis d\u2019accord. Oui, la situation est surr\u00e9aliste. Par contre, Richter a souvent r\u00e9ussi \u00e0 aider ses clients \u00e0 traverser les crises. Apr\u00e8s tout, c\u2019est ce que nous faisons jour apr\u00e8s jour depuis pr\u00e8s de 95\u00a0ans. Nous voyons ces fluctuations \u00e9conomiques comme le moment parfait pour chercher des occasions de placement pour nos clients, afin de les aider \u00e0 tirer le maximum de leur portefeuille. Gr\u00e2ce au mod\u00e8le d\u2019architecture ouverte que nous appliquons en tout temps, nous sommes en mesure de rep\u00e9rer des solutions de placement hors pair provenant des quatre\u00a0coins du monde. Comme les march\u00e9s r\u00e9agissent diff\u00e9remment \u00e0 diff\u00e9rents moments, nous arrivons g\u00e9n\u00e9ralement \u00e0 d\u00e9couvrir des occasions. En plus de l\u2019exp\u00e9rience que nous avons acquise et du soutien que nous offrons aux entreprises familiales en p\u00e9riode de crise, les familles que nous accompagnons peuvent \u00e9galement compter sur notre approche client. Lorsque nous offrons \u00e0 nos clients des services de planification financi\u00e8re, nous nous arr\u00eatons \u00e0 tous les aspects. Nous nous effor\u00e7ons d\u2019aller au-del\u00e0 des chiffres. Il n\u2019y a pas que les portefeuilles des clients qui sont uniques; leur situation, leur dynamique familiale et leur style de vie le sont tout autant. Il faut voir au-del\u00e0 des rendements et tenir compte de la structure familiale, du style de vie et de la prochaine g\u00e9n\u00e9ration. Nous savons que les clients tiennent \u00e0 ce que leurs objectifs s\u2019inscrivent dans une suite logique et que leur portefeuille contribue \u00e0 leur style de vie. Alors, crise ou non, nous veillons \u00e0 ce que les occasions de placement r\u00e9pondent \u00e0 leurs besoins et s\u2019int\u00e8grent bien \u00e0 leur planification financi\u00e8re.<\/p>\n<p><strong>Quel est l\u2019avantage de diversifier notre portefeuille?<\/strong><\/p>\n<p><strong>KS\u00a0:<\/strong> En bref, r\u00e9partir les placements entre plusieurs cat\u00e9gories d\u2019actif peut aider les clients \u00e0 continuer de s\u2019approcher de leurs objectifs financiers lorsque la conjoncture \u00e9conomique est difficile. Constituer un portefeuille diversifi\u00e9 n\u2019est pas une mince affaire. Lorsque nous rencontrons les clients en vue de la construction de leur portefeuille, nous tenons compte de nombreux facteurs\u00a0: leurs objectifs \u00e0 court et \u00e0 long terme, leur style de vie, leur dynamique familiale et leurs valeurs, pour ne nommer que ceux-l\u00e0. Puis, selon leur histoire et leurs objectifs, nous cherchons des titres et des gestionnaires qui leur conviennent. Il n\u2019existe pas vraiment de solution cl\u00e9 en main pour construire un portefeuille diversifi\u00e9, tout est plut\u00f4t une question de personnalisation. C\u2019est dans ce domaine que le BFR aide les familles \u00e0 devenir r\u00e9ellement prosp\u00e8res. Comme nous n\u2019avons pas les mains li\u00e9es, nous avons acc\u00e8s aux meilleurs gestionnaires et solutions des quatre coins du monde. Nous b\u00e9n\u00e9ficions \u00e9galement du soutien inestimable d\u2019un vaste \u00e9ventail d\u2019experts provenant d\u2019autres \u00e9quipes de Richter, qui sont pr\u00eats \u00e0 faire profiter nos clients de leurs conseils et de leurs contacts. Nous \u00e9valuons chaque occasion en tenant compte de leur traitement fiscal et nous nous assurons qu\u2019elle cadre bien avec les placements existants. Comme nous ne g\u00e9rons aucune solution \u00e0 l\u2019interne et que nous n\u2019avons aucune relation strat\u00e9gique avec les fournisseurs de services financiers, les familles que nous accompagnons peuvent avoir la certitude que nous agissons uniquement dans leurs int\u00e9r\u00eats.<\/p>\n<p><a href=\"https:\/\/www.richter.ca\/fr\/solutions\/bureau-de-la-famille\/www-cindyboycephoto-com-33-2\/\" rel=\"attachment wp-att-12789\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12789 size-medium\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg\" alt=\"Un membre de l'\u00e9quipe qui lis sur son ordinateur et qui prend des notes \" width=\"600\" height=\"400\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg 600w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-1024x683.jpg 1024w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-768x512.jpg 768w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-1536x1024.jpg 1536w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Toujours dans cet esprit de personnalisation, sachez que toutes les familles qui ont recours \u00e0 nos services sont diff\u00e9rentes. Chacune d\u2019entre elles suit une voie qui lui est propre. Nous pourrions recommander un placement \u00e0 une famille que nous \u00e9viterions de sugg\u00e9rer \u00e0 une autre, et ce, simplement parce que leurs portefeuilles et leurs besoins ne sont pas les m\u00eames. Il n\u2019y a pas de solution universelle. Les familles que nous conseillons ne sont pas tenues d\u2019investir uniquement dans les produits d\u2019une seule institution ou soci\u00e9t\u00e9 financi\u00e8re.<\/p>\n<p><strong>Comment le risque a-t-il \u00e9volu\u00e9 et que peuvent faire les familles pour s\u2019y adapter? <\/strong><\/p>\n<p><strong>RL\u00a0:<\/strong> La v\u00e9ritable question ici est plut\u00f4t\u00a0: qu\u2019est-ce que le \u00ab\u00a0risque\u00a0\u00bb pour nos clients? Pour certains, le risque est une question de perte de capital et pour d\u2019autres, il tient davantage \u00e0 l\u2019impossibilit\u00e9 de financer leur mode de vie. D\u2019autres encore l\u2019associent \u00e0 la planification successorale et au transfert de patrimoine \u00e0 la prochaine g\u00e9n\u00e9ration ou \u00e0 l\u2019incertitude qui les entoure. La notion de risque est propre \u00e0 chaque famille. C\u2019est pourquoi diff\u00e9rents facteurs de risque entra\u00eeneront diff\u00e9rentes mesures. Ce n\u2019est pas vraiment une question d\u2019adaptation. Il faut plut\u00f4t d\u00e9finir et \u00e9valuer les types de risque qui touchent chacun de nos clients. Nous vous encourageons \u00e0 y pr\u00eater attention lorsque vous communiquez avec nos clients. En \u00e9tablissant des liens \u00e9troits avec les familles, nous pouvons engager un dialogue qui nous permet de comprendre leur perception des risques et leur tol\u00e9rance \u00e0 chacun des risques per\u00e7us. Nous sommes ainsi en mesure de cr\u00e9er des portefeuilles personnalis\u00e9s qui refl\u00e8tent les objectifs \u00e0 court et \u00e0 long terme de la famille tout en tenant compte de la r\u00e9partition du risque.<\/p>\n<p><strong>Comment le BFR aide-t-il les investisseurs \u00e0 att\u00e9nuer les risques li\u00e9s \u00e0 un placement? <\/strong><\/p>\n<p><strong>KS\u00a0:<\/strong> Puisque nous conseillons des familles, nous encourageons le dialogue ouvert avec nos clients dans le but d\u2019\u00e9valuer pr\u00e9cis\u00e9ment leurs objectifs et de veiller \u00e0 ce que leur structure de placement soit un gage de succ\u00e8s \u00e0 long terme. Nous nous penchons sur une gamme de risques et d\u2019objectifs avant de proposer une occasion de placement \u00e0 notre client\u00e8le. Cette approche nous permet de g\u00e9rer les portefeuilles en amont plut\u00f4t qu\u2019en aval. En nous montrant compr\u00e9hensifs envers le style de vie, les besoins et les objectifs de nos clients, nous favorisons un dialogue ouvert, qui est, selon nous, essentiel pour nous positionner comme conseiller de confiance aupr\u00e8s de nos clients. Former la prochaine g\u00e9n\u00e9ration est un autre moyen que nous pouvons prendre pour att\u00e9nuer les risques. Malheureusement, peu de familles y songent lorsqu\u2019il est question de risque. Est-ce que la prochaine g\u00e9n\u00e9ration est pr\u00eate \u00e0 prendre les r\u00eanes de son avenir financier? Les enfants et les petits-enfants vont-ils dilapider le patrimoine ou chercheront-ils \u00e0 leur tour \u00e0 cr\u00e9er de la richesse? Nous offrons le <a href=\"https:\/\/www.richter.ca\/fr\/solutions\/programme-de-litteratie-financiere\/\" target=\"_blank\" rel=\"noopener noreferrer\">Programme de litt\u00e9ratie financi\u00e8re<\/a>, qui permet aux participants de puiser des connaissances \u00e0 m\u00eame nos ressources de pointe et nos experts chevronn\u00e9s, dans un environnement d\u00e9pourvu de toute sollicitation. Les modules de formation permettent d\u2019en apprendre davantage sur les occasions, les enjeux et les d\u00e9fis li\u00e9s \u00e0 la gestion d\u2019une entreprise familiale ou d\u2019un patrimoine consid\u00e9rable ainsi que sur les risques et les responsabilit\u00e9s qui en d\u00e9coulent. Lorsque la prochaine g\u00e9n\u00e9ration est bien renseign\u00e9e et se sent pr\u00eate \u00e0 assumer les responsabilit\u00e9s qui l\u2019attendent, elle est moins susceptible de faire des choix ou de prendre des d\u00e9cisions de placement discutables.<\/p>\n<blockquote>\n<h3 style=\"padding-left: 40px;\"><span style=\"font-size: 30px;\">Il faut voir au-del\u00e0 des rendements et tenir compte de la structure familiale, du style de vie et de la prochaine g\u00e9n\u00e9ration.<\/span><\/h3>\n<\/blockquote>\n<p><strong>RL\u00a0:<\/strong> Nous aidons \u00e9galement \u00e0 att\u00e9nuer les risques li\u00e9s aux placements gr\u00e2ce \u00e0 notre approche souple et judicieuse. Le portefeuille de chaque famille doit refl\u00e9ter ses besoins et ses objectifs. Plus important encore, nous savons qu\u2019en tant que conseillers, nous sommes tenus de nous en remettre au jugement de nos clients. C\u2019est pourquoi nous cherchons continuellement \u00e0 obtenir leur r\u00e9troaction. Les familles nous font confiance, alors nous devons faire preuve de transparence et encourager le dialogue pour que chaque d\u00e9cision de placement soit approuv\u00e9e par nos clients. Nous travaillons \u00e9troitement avec les familles pour int\u00e9grer leurs placements existants \u00e0 leur plan, et nous veillons \u00e0 ce que tous les changements apport\u00e9s soient strat\u00e9giques et aient le moins de r\u00e9percussions fiscales possible. Nous pr\u00e9sentons uniquement de nouveaux placements \u00e0 nos clients apr\u00e8s que notre <a href=\"https:\/\/www.richter.ca\/fr\/controle-diligent-des-gestionnaires-de-portefeuille\/\" target=\"_blank\" rel=\"noopener noreferrer\">recherche approfondie et notre contr\u00f4le diligent<\/a> sont termin\u00e9s. Puis nous int\u00e9grons les placements aux portefeuilles seulement si nous avons l\u2019autorisation de nos clients, car notre r\u00f4le consiste, selon nous, \u00e0 aider nos clients \u00e0 bien comprendre leur situation financi\u00e8re et \u00e0 en tenir les commandes.<\/p>\n<p>&nbsp;<\/p>\n<h3>Consultez \u00e9galement les articles suivants :<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/solutions\/bureau-de-la-famille\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bureau familial Richter<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/solutions\/gerer-votre-patrimoine\/\" target=\"_blank\" rel=\"noopener noreferrer\">G\u00e9r\u00e9r votre patrimoine<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/goals\/mon-portfolio-est-devenu-trop-complexe-comment-obtenir-une-meilleure-vue-densemble-et-massurer-que-je-profite-des-meilleures-strategies-de-placement-disponibles\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comment puis-je obtenir une meilleure vue d\u2019ensemble de mon portefeuille de placements?<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/goals\/comme-tout-le-monde-je-souhaite-tirer-le-maximum-de-mes-placements-pour-assurer-lavenir-financier-de-ma-famille\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comment puis-je maximiser mes investissements?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses. Votre fa\u00e7on de voir les choses peut changer rapidement selon que vous, votre entreprise et votre famille vous trouviez au sommet ou au creux de la vague. Pour affronter les temp\u00eates \u00e9conomiques, mieux [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1360],"class_list":["post-13068","insights","type-insights","status-publish","hentry","insights-type-gerer-votre-patrimoine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Optimiser les portefeuilles et repenser le risque - Richter<\/title>\n<meta name=\"description\" content=\"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimiser les portefeuilles et repenser le risque - Richter\" \/>\n<meta property=\"og:description\" content=\"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T19:12:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/\",\"name\":\"Optimiser les portefeuilles et repenser le risque - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/boyce_cindy_6206-600x400.jpg\",\"datePublished\":\"2020-06-24T20:56:42+00:00\",\"dateModified\":\"2021-07-21T19:12:01+00:00\",\"description\":\"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/boyce_cindy_6206-600x400.jpg\",\"contentUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/boyce_cindy_6206-600x400.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/optimiser-les-portefeuilles-et-repenser-le-risque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Optimiser les portefeuilles et repenser le risque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optimiser les portefeuilles et repenser le risque - Richter","description":"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Optimiser les portefeuilles et repenser le risque - Richter","og_description":"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-07-21T19:12:01+00:00","og_image":[{"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/","name":"Optimiser les portefeuilles et repenser le risque - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/#primaryimage"},"thumbnailUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg","datePublished":"2020-06-24T20:56:42+00:00","dateModified":"2021-07-21T19:12:01+00:00","description":"Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes Les placements et la gestion de portefeuille sont parfois frapp\u00e9s par de v\u00e9ritables raz-de-mar\u00e9e, entra\u00een\u00e9s dans des mont\u00e9es et des descentes vertigineuses.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/#primaryimage","url":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg","contentUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/05\/boyce_cindy_6206-600x400.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/optimiser-les-portefeuilles-et-repenser-le-risque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Optimiser les portefeuilles et repenser le risque"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/13068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=13068"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=13068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}