{"id":19532,"date":"2022-03-13T22:34:20","date_gmt":"2022-03-13T21:34:20","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=insights&#038;p=19532"},"modified":"2022-03-17T05:48:12","modified_gmt":"2022-03-17T04:48:12","slug":"est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/","title":{"rendered":"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS?"},"content":{"rendered":"<div class=\"bl-wysiwyg animaenter wrapper\">\n    <p>Le contexte fiscal change constamment. De nouveaux gouvernements, de nouvelles lois et de nouveaux \u00e9v\u00e9nements personnels exercent des pressions sur votre famille et votre entreprise. Vous avez peut-\u00eatre une solide strat\u00e9gie de placement en place, mais tient-elle compte de la nouvelle r\u00e9glementation? A-t-elle \u00e9t\u00e9 examin\u00e9e d\u2019un point de vue fiscal? Bien s\u00fbr, vos placements offrent un rendement raisonnable, mais apr\u00e8s avoir pay\u00e9 les imp\u00f4ts, le taux de rendement est nettement moins avantageux que vous le souhaiteriez. En ce qui a trait \u00e0 la planification fiscale, vos collaborateurs et vous devez vous parler r\u00e9guli\u00e8rement pour rester \u00e0 l\u2019aff\u00fbt des nombreuses aubaines fiscales qui pourraient se pr\u00e9senter et vous permettre de pour r\u00e9duire votre fardeau fiscal. Dans ce cas, pourquoi avez-vous l\u2019impression que votre conseiller financier ne vous donne pas une vue d\u2019ensemble en ce qui concerne l\u2019imposition de vos placements?<\/p>\n<p>Beaucoup d\u2019\u00e9l\u00e9ments doivent \u00eatre pris en consid\u00e9ration, qui vont au-del\u00e0 de l\u2019\u00e9valuation des m\u00e9rites d\u2019une strat\u00e9gie de placement couronn\u00e9e de succ\u00e8s. Le Bureau familial Richter peut vous aider \u00e0 vous y retrouver. Avant de proposer une solution de placement, nous en faisons toujours l\u2019examen \u00e0 l\u2019aune de notre <a href=\"https:\/\/www.richter.ca\/fr\/controle-diligent-des-gestionnaires-de-portefeuille\/\">processus exhaustif de recherche et de diligence raisonnable.<\/a> Nous l\u2019\u00e9valuons d\u2019un point de vue fiscal afin de nous assurer qu\u2019elle correspond \u00e0 votre capacit\u00e9 de risque et qu\u2019elle s\u2019ins\u00e8re bien dans votre strat\u00e9gie \u00e0 long terme. Nous vous pr\u00e9sentons toujours une vue d\u2019ensemble et communiquons avec vous \u00e0 chaque \u00e9tape du processus.<\/p>\n<p>Il est bien s\u00fbr important de choisir o\u00f9 et comment investir votre argent, mais la structure de vos placements, qu\u2019ils soient d\u00e9tenus en votre nom ou celui de l\u2019entreprise, a aussi une incidence tangible d\u2019un point de vue fiscal. Richter peut vous guider et vous aider \u00e0 profiter de strat\u00e9gies de placement con\u00e7ues sp\u00e9cialement pour vous offrir un rendement apr\u00e8s imp\u00f4t optimal.<\/p>\n<\/div>\n\n<div class=\"experts-carousel\">\n    <div class=\"wrapper\">\n                <div class=\"tt-cta\">\n            <h2>EXPERTS CL\u00c9S<\/h2>            <a href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/\" class=\"arrow-l\">Afficher tout<\/a>\n        <\/div>\n    <\/div>\n                <div class=\"experts wrapper slickCarouselCustom\">\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/mindy-mayman\/\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/06\/mindy_mayman_site-web-740-x-640-px.webp\" alt=\"\">\n                    <div class=\"content\">\n                        <h3>Mindy Mayman<\/h3>\n                        <div class=\"ql\">B.A. \u00c9conomie, Pl. Fin., FMA, CIM<\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/greg-moore\/\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/greg_moore_site-web-740-x-640-px.webp\" alt=\"\">\n                    <div class=\"content\">\n                        <h3>Greg Moore<\/h3>\n                        <div class=\"ql\">CFA<\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/danny-ritter\/\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/06\/ritter_danny_web_740x640px-1.png\" alt=\"\">\n                    <div class=\"content\">\n                        <h3>Danny Ritter<\/h3>\n                        <div class=\"ql\">CPA, CFA<\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"\" alt=\"\">\n                    <div class=\"content\">\n                        <h3><\/h3>\n                        <div class=\"ql\"><\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/athas-kouvaras\/\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2020\/11\/athas_kouvaras_site-web-740-x-640-px.webp\" alt=\"\">\n                    <div class=\"content\">\n                        <h3>Athas Kouvaras<\/h3>\n                        <div class=\"ql\">CAIA, CIM<\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                <\/div>\n    <\/div>\n\n<div class=\"bl-expertise animaenter wrapper\">\n        <span class=\"sup-title\">SERVICES<\/span>    <h2 class=\"\">EXPERTISES ASSOCI\u00c9ES<\/h2>                <div class=\"listing\">\n                            <a href=\"https:\/\/www.richter.ca\/fr\/bureau-familial\/creer-et-gerer-votre-patrimoine\/\" class=\"item\">\n                    <h3>Cr\u00e9er et g\u00e9rer votre patrimoine<\/h3>\n                    <p>Depuis toujours, nous sommes guid\u00e9s par l\u2019ind\u00e9pendance et l\u2019objectivit\u00e9. Nous ne sommes pas redevables \u00e0 une solution d&rsquo;investissement ou limit\u00e9s par le nombre d&rsquo;opportunit\u00e9s d&rsquo;investissement disponibles sur le march\u00e9.<\/p>\n                <\/a>\n                            <a href=\"https:\/\/www.richter.ca\/fr\/bureau-familial\/planification-successorale-et-fiscale-pour-proteger-votre-patrimoine\/\" class=\"item\">\n                    <h3>Planification successorale et fiscale pour prot\u00e9ger votre patrimoine<\/h3>\n                    <p>L\u2019int\u00e9gration des strat\u00e9gies et structures fiscales est essentielle pour toutes les familles tr\u00e8s fortun\u00e9es. Ces strat\u00e9gies comprennent la planification testamentaire et successorale, l\u2019utilisation de fiducies, l\u2019optimisation des structures de placement, \u00e9l\u00e9ments permettant d\u2019augmenter l\u2019efficience fiscale et de r\u00e9duire le fardeau fiscal pour vous et les g\u00e9n\u00e9rations suivantes.<\/p>\n                <\/a>\n                    <\/div>        \n    <\/div>\n\n<div class=\"bl-articles animaenter\">\n    <div class=\"wrapper\">    \n        <div class=\"tt-cta\">\n            <h2>R\u00c9FLEXIONS CONNEXES<\/h2>            <a class=\"arrow-l\" target=\"\" href=\"https:\/\/www.richter.ca\/fr\/nos-reflexions\/\">D\u00e9couvrez d&rsquo;autres publications<\/a>        <\/div>\n        \n        \n        <div class=\"tt-cta-r\">\n            <a target=\"\" href=\"#main-footer\">Tenez-moi au courant<\/a>        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le contexte fiscal change constamment. De nouveaux gouvernements, de nouvelles lois et de nouveaux \u00e9v\u00e9nements personnels exercent des pressions sur votre famille et votre entreprise. Vous avez peut-\u00eatre une solide strat\u00e9gie de placement en place, mais tient-elle compte de la nouvelle r\u00e9glementation?<\/p>\n","protected":false},"featured_media":19825,"template":"","insights-type":[1360],"class_list":["post-19532","insights","type-insights","status-publish","has-post-thumbnail","hentry","insights-type-gerer-votre-patrimoine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter<\/title>\n<meta name=\"description\" content=\"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter\" \/>\n<meta property=\"og:description\" content=\"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T04:48:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2022\/03\/shutterstock_83018101.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1078\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/\",\"name\":\"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shutterstock_83018101.jpg\",\"datePublished\":\"2022-03-13T21:34:20+00:00\",\"dateModified\":\"2022-03-17T04:48:12+00:00\",\"description\":\"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shutterstock_83018101.jpg\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shutterstock_83018101.jpg\",\"width\":1078,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter","description":"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter","og_description":"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2022-03-17T04:48:12+00:00","og_image":[{"width":1078,"height":719,"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2022\/03\/shutterstock_83018101.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/","name":"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS? - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/#primaryimage"},"thumbnailUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2022\/03\/shutterstock_83018101.jpg","datePublished":"2022-03-13T21:34:20+00:00","dateModified":"2022-03-17T04:48:12+00:00","description":"Les strat\u00e9gies d\u2019investissement avis\u00e9es doivent tenir compte des d\u00e9clarations de revenus. Richter \u00e9value vos placements en tenant compte de leur traitement fiscal pour veiller \u00e0 ce qu\u2019ils r\u00e9pondent aux besoins de votre famille.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/#primaryimage","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2022\/03\/shutterstock_83018101.jpg","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2022\/03\/shutterstock_83018101.jpg","width":1078,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/est-ce-que-je-paie-le-bon-montant-en-impot-pour-mes-placements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"EST-CE QUE JE PAIE LE BON MONTANT EN IMP\u00d4T POUR MES PLACEMENTS?"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/19532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media\/19825"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=19532"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=19532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}