{"id":24546,"date":"2024-02-09T19:36:23","date_gmt":"2024-02-09T18:36:23","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=insights&#038;p=24546"},"modified":"2024-02-09T19:36:25","modified_gmt":"2024-02-09T18:36:25","slug":"les-nouvelles-regles-de-rdeif-sont-en-vigueur","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/","title":{"rendered":"Les nouvelles r\u00e8gles de RDEIF sont en vigueur"},"content":{"rendered":"<div class=\"bl-wysiwyg animaenter wrapper\">\n    <h3>Ce que vous devez savoir<\/h3>\n<p>Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab\u00a0RDEIF\u00a0\u00bb). Les RDEIF limiteront la d\u00e9duction des d\u00e9penses d\u2019int\u00e9r\u00eats et de financement \u00e0 30\u00a0% du revenu imposable rajust\u00e9, qui \u00e9quivaut g\u00e9n\u00e9ralement au BAIIA \u00e9tabli aux fins de l\u2019imp\u00f4t au Canada.<\/p>\n<p>Les d\u00e9penses d\u2019int\u00e9r\u00eats et de financement n\u2019incluront pas les co\u00fbts de financement entre les membres d\u2019un groupe, par exemple, les pr\u00eats entre une soci\u00e9t\u00e9 m\u00e8re canadienne et sa filiale canadienne, pourvu qu\u2019un choix soit fait en temps opportun. D\u2019autres \u00e9l\u00e9ments comme les frais de location, les int\u00e9r\u00eats capitalis\u00e9s et les reports de pertes pourraient \u00eatre touch\u00e9s.<\/p>\n<p>Il y a aussi de bonnes nouvelles puisque les r\u00e8gles de RDEIF permettent le partage de la capacit\u00e9 exc\u00e9dentaire au sein des membres <em>li\u00e9s<\/em> et <em>affili\u00e9s<\/em> du groupe. Ainsi, lorsqu\u2019une entit\u00e9 du groupe a des frais d\u2019int\u00e9r\u00eats et de financement d\u00e9passant la limite de 30\u00a0%, une autre entit\u00e9 du groupe qui dispose d\u2019un revenu imposable rajust\u00e9 plus que suffisant pourra absorber l\u2019exc\u00e9dent. Ce partage de la capacit\u00e9 exc\u00e9dentaire se veut un moyen d\u2019att\u00e9nuer l\u2019incidence de ces r\u00e8gles, bien qu\u2019il n\u00e9cessite le d\u00e9p\u00f4t de divers formulaires prescrits et d\u00e9signations en temps opportun.<\/p>\n<p>Les r\u00e8gles de RDEIF s\u2019appliqueront aux ann\u00e9es d\u2019imposition des soci\u00e9t\u00e9s et des fiducies qui commencent \u00e0 compter du 1<sup>er<\/sup>\u00a0octobre\u00a02023 ou apr\u00e8s cette date.<\/p>\n<p>Les r\u00e8gles ne s\u2019appliqueront pas aux \u00ab\u00a0entit\u00e9s exclues\u00a0\u00bb d\u00e9finies comme suit\u00a0:<\/p>\n<ul>\n<li>Les <em>soci\u00e9t\u00e9s priv\u00e9es sous contr\u00f4le canadien<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a><\/em> qui, avec toutes leurs soci\u00e9t\u00e9s <em>associ\u00e9es<\/em>, ont un <em>capital imposable<\/em> combin\u00e9 de moins de 50\u00a0millions de dollars.<\/li>\n<li>Les groupes <em>li\u00e9s<\/em> ou <em>affili\u00e9s<\/em> d\u2019entit\u00e9s qui ont des d\u00e9penses d\u2019int\u00e9r\u00eats et de financement nettes des int\u00e9r\u00eats et des revenus de financement de moins de 1\u00a0million de dollars.<\/li>\n<li>Les soci\u00e9t\u00e9s et fiducies r\u00e9sidentes du Canada ainsi que toutes leurs entit\u00e9s r\u00e9sidentes du Canada <em>li\u00e9es <\/em>et <em>affili\u00e9es<\/em>, \u00e0 condition que chacune d\u2019elles remplisse toutes les conditions suivantes\u00a0:\n<ul>\n<li>Au moins 90\u00a0% des activit\u00e9s et entreprises sont exploit\u00e9es au Canada;<\/li>\n<li>La valeur comptable, d\u00e9termin\u00e9e selon les principes comptables g\u00e9n\u00e9ralement reconnus, de toute <em>soci\u00e9t\u00e9 \u00e9trang\u00e8re affili\u00e9e<\/em> ou la proportion de la juste valeur marchande des actifs de cette <em>soci\u00e9t\u00e9 \u00e9trang\u00e8re affili\u00e9e<\/em> n\u2019est pas sup\u00e9rieure \u00e0 5\u00a0millions de dollars;<\/li>\n<li>Aucune soci\u00e9t\u00e9 du groupe <em>li\u00e9<\/em> ou <em>affili\u00e9<\/em> n\u2019a un groupe <em>li\u00e9<\/em> d\u2019actionnaires non-r\u00e9sidents d\u00e9tenant 25\u00a0% ou plus des votes ou de la valeur de cette entit\u00e9;<\/li>\n<li>Aucune fiducie du groupe <em>li\u00e9<\/em> ou <em>affili\u00e9<\/em> n\u2019a un b\u00e9n\u00e9ficiaire non-r\u00e9sident ou un groupe <em>li\u00e9<\/em> de b\u00e9n\u00e9ficiaires non-r\u00e9sidents d\u00e9tenant 25\u00a0% ou plus des int\u00e9r\u00eats de la fiducie;<\/li>\n<li>Aucune soci\u00e9t\u00e9 de personnes dont plus de 50\u00a0% des parts de la soci\u00e9t\u00e9 en commandite sont d\u00e9tenues par des non-r\u00e9sidents ne poss\u00e8de des actions de soci\u00e9t\u00e9s ou des int\u00e9r\u00eats dans des fiducies qui r\u00e9pondent au crit\u00e8re de 25\u00a0% des votes et de la valeur;<\/li>\n<li>Au moins 90\u00a0% de toutes les d\u00e9penses d\u2019int\u00e9r\u00eats et de financement ne sont pas vers\u00e9es \u00e0 des non-r\u00e9sidents ayant un lien de d\u00e9pendance et \u00e0 des <em>entit\u00e9s exon\u00e9r\u00e9es d\u2019imp\u00f4t<\/em>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Comme on peut le constater en raison de l\u2019\u00e9troitesse de ces exceptions, il peut \u00eatre difficile d\u2019obtenir le statut d\u2019entit\u00e9 exclue.<\/p>\n<p>Les r\u00e8gles sont extr\u00eamement complexes et peuvent avoir une incidence consid\u00e9rable sur les flux de tr\u00e9sorerie, surtout dans les secteurs capitalistiques. Les taux d\u2019int\u00e9r\u00eat \u00e9lev\u00e9s qui devraient pr\u00e9valoir en 2024 augmenteront l\u2019incidence de ces r\u00e8gles. Les contribuables touch\u00e9s souhaiteront peut-\u00eatre consid\u00e9rer le capital-investissement au lieu du financement. Bien entendu, chaque contribuable doit \u00e9valuer l\u2019incidence du r\u00e9gime de RDEIF compte tenu de ses circonstances particuli\u00e8res. Comme pour toutes les modifications fiscales, nous vous recommandons de communiquer avec vos conseillers chez Richter pour d\u00e9terminer de quelle fa\u00e7on elles vous concernent et quelles mesures peuvent \u00eatre prises pour en diminuer l\u2019effet.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Les mots en italique sont des termes d\u00e9finis en vertu de la Loi de l\u2019imp\u00f4t sur le revenu, dont l\u2019explication d\u00e9passe la port\u00e9e du pr\u00e9sent article.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","insights-type":[1371],"class_list":["post-24546","insights","type-insights","status-publish","hentry","insights-type-optimiser-vos-activites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter<\/title>\n<meta name=\"description\" content=\"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter\" \/>\n<meta property=\"og:description\" content=\"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T18:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\\\/\",\"name\":\"Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2024-02-09T18:36:23+00:00\",\"dateModified\":\"2024-02-09T18:36:25+00:00\",\"description\":\"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les nouvelles r\u00e8gles de RDEIF sont en vigueur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter","description":"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter","og_description":"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2024-02-09T18:36:25+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/","name":"Les nouvelles r\u00e8gles de RDEIF sont en vigueur - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2024-02-09T18:36:23+00:00","dateModified":"2024-02-09T18:36:25+00:00","description":"Afin de se conformer aux lignes directrices internationales limitant le transfert de b\u00e9n\u00e9fices vers des r\u00e9gimes fiscaux plus avantageux, le minist\u00e8re des Finances a introduit les r\u00e8gles de restriction des d\u00e9penses excessives d\u2019int\u00e9r\u00eats et de financement (\u00ab RDEIF \u00bb).","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/les-nouvelles-regles-de-rdeif-sont-en-vigueur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Les nouvelles r\u00e8gles de RDEIF sont en vigueur"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/24546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=24546"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=24546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}