{"id":25406,"date":"2024-07-29T16:52:00","date_gmt":"2024-07-29T14:52:00","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=insights&#038;p=25406"},"modified":"2024-07-29T19:58:30","modified_gmt":"2024-07-29T17:58:30","slug":"etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/","title":{"rendered":"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE"},"content":{"rendered":"<div class=\"bl-wysiwyg animaenter wrapper\">\n    <p>Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques. <a href=\"https:\/\/www.cisecurity.org\/insights\/blog\/7-reasons-tabletop-exercises-are-a-must\" target=\"_blank\" rel=\"noopener\">L\u2019exercice de simulation de crise<\/a> constitue un moyen efficace pour am\u00e9liorer les capacit\u00e9s de gestion de crise d&rsquo;une organisation et promouvoir sa r\u00e9silience organisationnelle. Ces exercices de gestion de crise simulent des situations d\u2019urgence r\u00e9elles dans un environnement contr\u00f4l\u00e9 et ax\u00e9 sur la discussion, ce qui permet aux participants de mettre en pratique <a href=\"https:\/\/www.corporatecomplianceinsights.com\/cybersecurity-tabletop-exercises\/\" target=\"_blank\" rel=\"noopener\">leurs techniques de r\u00e9ponse, d\u2019identifier les faiblesses et d\u2019am\u00e9liorer la coordination et la communication<\/a> sans cons\u00e9quences r\u00e9elles.<\/p>\n<h2><span style=\"font-size: 24px\">La demande<\/span><\/h2>\n<p>Un client a retenu les services de Richter pour l\u2019aider \u00e0 effectuer un examen exhaustif de ses processus de gestion de crise, examen qui comprenait ce qui suit\u00a0:<\/p>\n<ol>\n<li>Une \u00e9valuation de la maturit\u00e9 de ses plans de r\u00e9ponse aux incidents, de continuit\u00e9 des activit\u00e9s et de gestion de crise<\/li>\n<li>La tenue d\u2019un exercice de simulation de crise con\u00e7u pour :\n<ul>\n<li>Clarifier les r\u00f4les et responsabilit\u00e9s en cas d\u2019inciden<\/li>\n<li>Tester la prise de d\u00e9cision<\/li>\n<li>Sensibiliser les responsables des interventions en cas d\u2019incident aux nouvelles menaces<\/li>\n<li>Satisfaire aux exigences contractuelles<\/li>\n<li>Identifier les aspects \u00e0 am\u00e9liorer<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<h2><span style=\"font-size: 24px\">Les r\u00e9sultats<\/span><\/h2>\n<p>Richter a collabor\u00e9 avec le client dans la conception et la r\u00e9alisation d\u2019un sc\u00e9nario d\u2019attaque par ran\u00e7ongiciel sur mesure, qui tenait compte des aspects propres \u00e0 son organisation, notamment\u00a0:<\/p>\n<ul>\n<li>Sa combinaison d\u2019infrastructures TI physique et infonuagique<\/li>\n<li>Ses capacit\u00e9s actuelles de surveillance de la s\u00e9curit\u00e9<\/li>\n<li>Ses plans, politiques et proc\u00e9dures de gestion de crise document\u00e9s<\/li>\n<li>Les types d\u2019informations personnelles et confidentielles qu\u2019elle conserve sur ses clients<\/li>\n<li>La pr\u00e9sence de fournisseurs de services de s\u00e9curit\u00e9 et d\u2019autres fournisseurs<\/li>\n<li>Les r\u00e9sultats de l\u2019\u00e9valuation de la maturit\u00e9<\/li>\n<\/ul>\n<p>En simulant une cyberattaque r\u00e9aliste et en comparant ses pratiques actuelles aux bonnes pratiques de l\u2019industrie, notre client a pu identifier les faiblesses critiques, am\u00e9liorer la coordination et augmenter son niveau de pr\u00e9paration globale, tout en recevant des recommandations concr\u00e8tes pour renforcer sa r\u00e9silience en mati\u00e8re de cybers\u00e9curit\u00e9, notamment\u00a0:<\/p>\n<ul>\n<li>\u00c9tablir des relations et des ententes contractuelles avec des organismes externes (comme des cabinets de relations publiques et des experts judiciaires)<\/li>\n<li>Mettre en place des cha\u00eenes de communication et tirer parti de la technologie pour assurer une divulgation rapide des incidents<\/li>\n<li>Mettre \u00e0 jour et am\u00e9liorer les plans et les proc\u00e9dures de gestion de crise existants en fonction des le\u00e7ons apprises<\/li>\n<\/ul>\n<p>Richter a \u00e9galement sensibilis\u00e9 les dirigeants de l\u2019organisation sur le sujet des ran\u00e7ongiciels, ainsi que sur les meilleures pratiques s\u2019y rapportant afin de se prot\u00e9ger et d\u2019att\u00e9nuer les risques associ\u00e9s \u00e0 de telles attaques.<\/p>\n<h2><span style=\"font-size: 24px\">Comment Richter peut aider<\/span><\/h2>\n<p>Votre organisation pourrait b\u00e9n\u00e9ficier de tests p\u00e9riodiques relativement aux politiques et proc\u00e9dures existantes en mati\u00e8re de gestion des incidents et de continuit\u00e9 des activit\u00e9s. Les experts en cybers\u00e9curit\u00e9 de Richter peuvent vous <a href=\"https:\/\/www.corporatecomplianceinsights.com\/cybersecurity-tabletop-exercises\/\" target=\"_blank\" rel=\"noopener\">aider \u00e0 cr\u00e9er et \u00e0 animer des exercices de simulation de crise<\/a> personnalis\u00e9s adapt\u00e9s \u00e0 votre secteur d&rsquo;activit\u00e9, en fournissant des conseils adapt\u00e9s et des recommandations d\u2019am\u00e9lioration.<\/p>\n<p>Si votre organisation ne dispose pas de plans document\u00e9s de r\u00e9ponse aux incidents, de continuit\u00e9 des activit\u00e9s ou de gestion de crise, nous pouvons \u00e9galement aider \u00e0 \u00e9laborer ces documents tout en les adaptant au contexte, \u00e0 la taille et \u00e0 la port\u00e9e de votre organisation.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques. L\u2019exercice de simulation de crise constitue un moyen efficace pour am\u00e9liorer les capacit\u00e9s de gestion de crise d\u2019une organisation et promouvoir sa r\u00e9silience organisationnelle. <\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1371,1356],"class_list":["post-25406","insights","type-insights","status-publish","hentry","insights-type-optimiser-vos-activites","insights-type-planification-de-la-transition-et-de-la-succession"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter<\/title>\n<meta name=\"description\" content=\"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter\" \/>\n<meta property=\"og:description\" content=\"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T17:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\\\/\",\"name\":\"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2024-07-29T14:52:00+00:00\",\"dateModified\":\"2024-07-29T17:58:30+00:00\",\"description\":\"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter","description":"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter","og_description":"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2024-07-29T17:58:30+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/","name":"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2024-07-29T14:52:00+00:00","dateModified":"2024-07-29T17:58:30+00:00","description":"Dans le monde actuel qui \u00e9volue rapidement et qui est impr\u00e9visible, les organisations doivent \u00eatre pr\u00eates \u00e0 faire face \u00e0 toute une gamme de crises potentielles, des catastrophes naturelles aux cyberattaques.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/etude-de-cas-assurer-la-continuite-des-activites-grace-a-des-exercices-de-simulation-de-crise-sur-mesure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"\u00c9TUDE DE CAS\u00a0: ASSURER LA CONTINUIT\u00c9 DES ACTIVIT\u00c9S GR\u00c2CE \u00c0 DES EXERCICES DE SIMULATION DE CRISE SUR MESURE"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/25406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=25406"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=25406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}