{"id":26622,"date":"2025-02-18T19:09:53","date_gmt":"2025-02-18T18:09:53","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=insights&#038;p=26622"},"modified":"2025-03-05T20:08:01","modified_gmt":"2025-03-05T19:08:01","slug":"communique-presse-conference-sohn","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/","title":{"rendered":"Communiqu\u00e9 de presse &#8211; La conf\u00e9rence d&rsquo;investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l&rsquo;\u00e9v\u00e9nement inaugural 2025"},"content":{"rendered":"<div class=\"bl-wysiwyg animaenter wrapper\">\n    <p>Montr\u00e9al, le 18 f\u00e9vrier 2025 \u2014 Richter Bureau Familial | d&rsquo;Affaires, est fier de co-pr\u00e9senter la conf\u00e9rence inaugurale d&rsquo;investissement Sohn Montr\u00e9al, qui se tiendra le 28 mai 2025 \u00e0 l&rsquo;h\u00f4tel Four Seasons Montr\u00e9al. Cet \u00e9v\u00e9nement marquant r\u00e9unira des investisseurs, des gestionnaires d&rsquo;actifs et des experts financiers de toute l&rsquo;Am\u00e9rique du Nord pour partager leurs id\u00e9es d&rsquo;investissement les plus percutantes, tout en soutenant une cause essentielle : la recherche p\u00e9diatrique dans les h\u00f4pitaux montr\u00e9alais.<\/p>\n<p>En ligne avec la tradition d&rsquo;excellence et d&rsquo;innovation de Richter, la conf\u00e9rence mettra en lumi\u00e8re les tendances cl\u00e9s qui fa\u00e7onneront les march\u00e9s financiers en 2025. Elle offrira une occasion unique aux professionnels de r\u00e9seauter et de s&rsquo;inspirer des leaders de l&rsquo;industrie. L&rsquo;int\u00e9gralit\u00e9 des profits de l&rsquo;\u00e9v\u00e9nement sera revers\u00e9e \u00e0 l&rsquo;H\u00f4pital Sainte-Justine et \u00e0 l&rsquo;H\u00f4pital de Montr\u00e9al pour enfants, contribuant ainsi aux avanc\u00e9es continues en mati\u00e8re de soins p\u00e9diatriques et de recherche m\u00e9dicale.<\/p>\n<p>\u00ab Sohn Montr\u00e9al promet d\u2019\u00eatre une addition innovante \u00e0 la s\u00e9rie de conf\u00e9rences internationales Sohn. Nous r\u00e9unissons un groupe d\u2019investisseurs de renomm\u00e9e internationale qui partageront leurs meilleures id\u00e9es, en plus de discussions sur les secteurs d\u2019investissement cl\u00e9s en 2025 \u00bb, a d\u00e9clar\u00e9 Anik Lanthier, associ\u00e9e et cheffe des placements chez Richter.<\/p>\n<p><a href=\"https:\/\/www.businesswire.com\/news\/home\/20250218362012\/fr\/\">Lisez le communiqu\u00e9 complet<\/a> pour en savoir plus sur la conf\u00e9rence d&rsquo;investissement Sohn Montr\u00e9al 2025 et d\u00e9couvrir comment vous pouvez participer \u00e0 cette initiative d&rsquo;impact.<\/p>\n<\/div>\n\n<div class=\"experts-carousel\">\n    <div class=\"wrapper\">\n                <div class=\"tt-cta\">\n                        <a href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/\" class=\"arrow-l\">Afficher tout<\/a>\n        <\/div>\n    <\/div>\n                <div class=\"experts wrapper slickCarouselCustom\">\n                    <a tabindex=\"-1\" class=\"carousel-item\" href=\"https:\/\/www.richter.ca\/fr\/nos-experts\/anik-lanthier\/\">\n                <div class=\"image\">\n                                        <img decoding=\"async\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2024\/01\/anik_lanthiel_site-web-740-x-640-px.webp\" alt=\"\">\n                    <div class=\"content\">\n                        <h3>Anik Lanthier<\/h3>\n                        <div class=\"ql\">M.Sc, CFA<\/div>\n                    <\/div>\n                <\/div>\n            <\/a>\n                <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","insights-type":[1358],"class_list":["post-26622","insights","type-insights","status-publish","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Communiqu\u00e9 de presse - La conf\u00e9rence d&#039;investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l&#039;\u00e9v\u00e9nement inaugural 2025 - Richter<\/title>\n<meta name=\"description\" content=\"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d&#039;investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communiqu\u00e9 de presse - La conf\u00e9rence d&#039;investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l&#039;\u00e9v\u00e9nement inaugural 2025 - Richter\" \/>\n<meta property=\"og:description\" content=\"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d&#039;investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T19:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/communique-presse-conference-sohn\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/communique-presse-conference-sohn\\\/\",\"name\":\"Communiqu\u00e9 de presse - La conf\u00e9rence d'investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l'\u00e9v\u00e9nement inaugural 2025 - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2025-02-18T18:09:53+00:00\",\"dateModified\":\"2025-03-05T19:08:01+00:00\",\"description\":\"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d'investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/communique-presse-conference-sohn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/communique-presse-conference-sohn\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/communique-presse-conference-sohn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Communiqu\u00e9 de presse &#8211; La conf\u00e9rence d&#8217;investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l&#8217;\u00e9v\u00e9nement inaugural 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Communiqu\u00e9 de presse - La conf\u00e9rence d'investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l'\u00e9v\u00e9nement inaugural 2025 - Richter","description":"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d'investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Communiqu\u00e9 de presse - La conf\u00e9rence d'investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l'\u00e9v\u00e9nement inaugural 2025 - Richter","og_description":"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d'investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2025-03-05T19:08:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/","name":"Communiqu\u00e9 de presse - La conf\u00e9rence d'investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l'\u00e9v\u00e9nement inaugural 2025 - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2025-02-18T18:09:53+00:00","dateModified":"2025-03-05T19:08:01+00:00","description":"Rejoignez Richter et les leaders financiers de renom \u00e0 la conf\u00e9rence inaugurale d'investissement Sohn Montr\u00e9al 2025, le 28 mai. D\u00e9couvrez les tendances du march\u00e9, d\u00e9veloppez votre r\u00e9seau et soutenez les h\u00f4pitaux p\u00e9diatriques montr\u00e9alais.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/communique-presse-conference-sohn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Communiqu\u00e9 de presse &#8211; La conf\u00e9rence d&#8217;investissement Sohn Montr\u00e9al annonce la liste de ses conf\u00e9renciers avec Richter comme co-pr\u00e9sentateur de l&#8217;\u00e9v\u00e9nement inaugural 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/26622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=26622"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=26622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}