{"id":5307,"date":"2018-09-07T22:57:09","date_gmt":"2018-09-07T20:57:09","guid":{"rendered":"https:\/\/www.richter.ca\/interviews\/stroll-for-kids\/"},"modified":"2022-03-13T23:37:10","modified_gmt":"2022-03-13T22:37:10","slug":"promenade-pour-les-petits","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/","title":{"rendered":"Promenade pour les petits"},"content":{"rendered":"<h2><strong>H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000 $ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2014 au 2017) \u2014 Cofondatrice | Depuis 2014<\/strong><\/h2>\n<h3><strong>1- Vous \u00eates cofondatrice de l\u2019\u00e9v\u00e9nement annuel Promenade pour les petits, une initiative qui a permis de r\u00e9unir plus de 500\u2009000 $ destin\u00e9s \u00e0 l\u2019H\u00f4pital de Montr\u00e9al pour enfants. Comment d\u00e9cririez-vous cette cause?<\/strong><\/h3>\n<p>La Promenade pour les petits est un \u00e9v\u00e9nement familial qui apporte une aide financi\u00e8re \u00e0 la Fondation Pour enfants seulement (\u00ab\u00a0PES\u00a0\u00bb) et \u00e0 l\u2019H\u00f4pital de Montr\u00e9al pour enfants. Les fonds recueillis sont utilis\u00e9s pour des programmes sp\u00e9ciaux, y compris le Parc des fr\u00e8res et s\u0153urs PES, et pour financer de l\u2019\u00e9quipement m\u00e9dical hautement prioritaire. En seulement trois ans, la Promenade pour les petits a permis de recueillir plus de 500\u2009000\u00a0$, devenant pour la Fondation PES un \u00e9v\u00e9nement annuel tr\u00e8s attendu. La Promenade pour les petits a attir\u00e9 plus de 150\u00a0familles, fournisseurs et commanditaires, des alli\u00e9s fid\u00e8les qui continuent de participer ann\u00e9e apr\u00e8s ann\u00e9e. En plus de r\u00e9unir des fonds pour des programmes et des \u00e9quipements importants, l\u2019un des objectifs de la Promenade pour les petits est d\u2019initier les enfants \u00e0 la philanthropie d\u00e8s le tout jeune \u00e2ge.<\/p>\n<h3><strong>2- Qu\u2019est-ce qui vous a incit\u00e9e \u00e0 vous engager aupr\u00e8s de l\u2019h\u00f4pital en particulier?<br \/>\n<\/strong><\/h3>\n<p>J\u2019ai cofond\u00e9 la Promenade pour les petits en 2014, apr\u00e8s la naissance de mes jumeaux pr\u00e9matur\u00e9s. Avi et Eli pesaient chacun moins de quatre livres \u00e0 la naissance, et ils ont pass\u00e9 six semaines dans l\u2019Unit\u00e9 de soins intensifs n\u00e9onatals. Lorsque Avi et Eli sont rentr\u00e9s \u00e0 la maison, je voulais exprimer ma gratitude \u00e0 l\u2019h\u00f4pital d\u2019une mani\u00e8re unique et significative \u2014 et c\u2019est ainsi que la Promenade pour les petits est n\u00e9e.<\/p>\n<p>J\u2019ai men\u00e9 le projet du Parc des fr\u00e8res et s\u0153urs PES apr\u00e8s l\u2019hospitalisation d\u2019un de mes jumeaux dans un h\u00f4pital am\u00e9ricain disposant d\u2019un programme similaire. Le Parc pourvoit aux besoins des familles des patients en se concentrant sur les fr\u00e8res et s\u0153urs en sant\u00e9, qui sont souvent oubli\u00e9s. Ce programme donne aux parents d\u00e9bord\u00e9s plus de temps pour continuer d\u2019entretenir les liens qu\u2019ils ont avec leur enfant hospitalis\u00e9, ce qui r\u00e9duit le stress caus\u00e9 par l\u2019argent et le temps n\u00e9cessaires pour obtenir un service de garde suppl\u00e9mentaire. Les fr\u00e8res et s\u0153urs peuvent rejoindre leurs parents \u00e0 l\u2019h\u00f4pital, o\u00f9 un groupe de professionnels de la garde d\u2019enfants s\u2019occupera d\u2019eux dans un milieu chaleureux et accueillant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15557 size-large\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-1024x576.jpg\" alt=\"Des membres de Richter l\u00e8vent des fonds pour l'h\u00f4pital pour enfants de Montr\u00e9al\" width=\"1024\" height=\"576\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-1024x576.jpg 1024w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-600x338.jpg 600w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-768x432.jpg 768w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-1536x864.jpg 1536w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_3-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2><\/h2>\n<h3><strong>3- \u00c0 votre avis, qu\u2019est-ce qui fait la force d\u2019une collectivit\u00e9?<br \/>\n<\/strong><\/h3>\n<p>La force de notre collectivit\u00e9 se mesure \u00e0 la fa\u00e7on dont nous prenons soin des personnes \u00e0 charge \u2014 les enfants, les personnes \u00e2g\u00e9es, ainsi que les personnes et les familles qui ont connu des difficult\u00e9s. Cela signifie qu\u2019il faut faire place aux membres de la collectivit\u00e9 qui ont besoin d\u2019aide. Pour \u00eatre forte, il faut qu\u2019une collectivit\u00e9 soit dispos\u00e9e \u00e0 apprendre, \u00e0 partager et \u00e0 valoriser la diversit\u00e9. Les membres doivent se conduire avec authenticit\u00e9 et d\u00e9termination.<\/p>\n<h3><strong>4- Quel conseil donneriez-vous aux gens qui songent \u00e0 lancer leur propre collecte de fonds pour une bonne cause?<br \/>\n<\/strong><\/h3>\n<p>\u00c7a prend un village \u2014 commencez par demander de l\u2019aide \u00e0 vos amis et \u00e0 votre famille. Vous rencontrerez en cours de route des personnes qui pensent comme vous, qui ont les comp\u00e9tences dont vous avez besoin et qui s\u2019int\u00e9ressent \u00e0 la cause. N\u2019ayez pas peur de demander des ressources \u2014 personne ne se fera une mauvaise opinion de vous, et les gens peuvent toujours refuser. Vous serez peut-\u00eatre surpris de voir combien de gens veulent vous aider. La Promenade pour les petits ne serait pas ce qu\u2019elle est aujourd\u2019hui sans le soutien incroyable du comit\u00e9 de planification, de la Fondation PES, de l\u2019H\u00f4pital, des familles participantes, ainsi que des milliers de commanditaires et donateurs.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15559 size-large\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-996x1024.jpg\" alt=\"Alana et des membres de Richter \u00e0 l'ext\u00e9rieur avec un tente Richter\" width=\"996\" height=\"1024\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-996x1024.jpg 996w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-583x600.jpg 583w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-50x50.jpg 50w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-768x790.jpg 768w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-1493x1536.jpg 1493w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_1-1-1991x2048.jpg 1991w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/><\/p>\n<h3><strong>5- Vous donnez \u00e9galement de votre temps \u00e0 la Fondation d\u2019Isra\u00ebl pour la recherche sur le cancer et \u00e0 l\u2019association montr\u00e9alaise pour les aveugles ; la Fondation MAB-Mackay. Pourquoi l\u2019engagement communautaire a-t-il autant d\u2019importance pour vous?<br \/>\n<\/strong><\/h3>\n<p>La g\u00e9n\u00e9rosit\u00e9, c\u2019est contagieux. Elle rend notre collectivit\u00e9 plus forte et plus unie. Gr\u00e2ce \u00e0 la collectivit\u00e9, j\u2019ai eu la chance d\u2019entendre parler de tellement de causes et de les soutenir, et d\u2019\u00e9changer avec des personnes merveilleuses. Ma famille b\u00e9n\u00e9ficie de nombreuses causes communautaires, et il est important pour nous de redonner \u00e0 la collectivit\u00e9, \u00e0 notre mani\u00e8re.<\/p>\n<p>D\u00e9couvrez le reportage de l\u2019\u00e9v\u00e9nement de l\u2019ann\u00e9e derni\u00e8re ici\u00a0:\u00a0<a href=\"https:\/\/www.btmontreal.ca\/videos\/just-for-kids-foundation-opens-sibling-park\/\">https:\/\/www.btmontreal.ca\/videos\/just-for-kids-foundation-opens-sibling-park\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000 $ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2014 au 2017) \u2014 Cofondatrice | Depuis 2014 1- Vous \u00eates cofondatrice de l\u2019\u00e9v\u00e9nement annuel Promenade pour les petits, une initiative qui a permis de r\u00e9unir plus de [&hellip;]<\/p>\n","protected":false},"featured_media":5266,"template":"","insights-type":[1358],"class_list":["post-5307","insights","type-insights","status-publish","has-post-thumbnail","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Promenade pour les petits - Richter<\/title>\n<meta name=\"description\" content=\"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promenade pour les petits - Richter\" \/>\n<meta property=\"og:description\" content=\"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-13T22:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/\",\"name\":\"Promenade pour les petits - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/web_communityprofiles_geller_alana_2.jpg\",\"datePublished\":\"2018-09-07T20:57:09+00:00\",\"dateModified\":\"2022-03-13T22:37:10+00:00\",\"description\":\"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/web_communityprofiles_geller_alana_2.jpg\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/web_communityprofiles_geller_alana_2.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Alana \u00e0 la promenade des enfants avec un ch\u00e8que g\u00e9ant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/promenade-pour-les-petits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Promenade pour les petits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Promenade pour les petits - Richter","description":"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Promenade pour les petits - Richter","og_description":"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2022-03-13T22:37:10+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/","name":"Promenade pour les petits - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/#primaryimage"},"thumbnailUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_2.jpg","datePublished":"2018-09-07T20:57:09+00:00","dateModified":"2022-03-13T22:37:10+00:00","description":"H\u00f4pital de Montr\u00e9al pour enfants \u2014 \u00c9v\u00e9nement communautaire \u2014 Promenade pour les petits de la Fondation PES (plus de 500\u2009000\u00a0$ ont \u00e9t\u00e9 collect\u00e9s pour l\u2019h\u00f4pital du 2015 au 2017) \u2014 Copr\u00e9sidente | Depuis 2015","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/#primaryimage","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_2.jpg","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/web_communityprofiles_geller_alana_2.jpg","width":2048,"height":1365,"caption":"Alana \u00e0 la promenade des enfants avec un ch\u00e8que g\u00e9ant"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/promenade-pour-les-petits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Promenade pour les petits"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/5307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media\/5266"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=5307"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=5307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}