{"id":5477,"date":"2018-09-19T16:31:08","date_gmt":"2018-09-19T14:31:08","guid":{"rendered":"https:\/\/www.richter.ca\/?p=5477"},"modified":"2021-08-02T18:38:02","modified_gmt":"2021-08-02T16:38:02","slug":"le-rgpd-changer-notre-vision-de-la-protection-des-donnees","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/","title":{"rendered":"Le RGPD : changer notre vision de la protection des donn\u00e9es"},"content":{"rendered":"<h2><strong>Mois de la cybers\u00e9curit\u00e9, Octobre 2017<\/strong><\/h2>\n<p>Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Toutefois, en raison de cet acc\u00e8s sans pr\u00e9c\u00e9dent, nous sommes de moins en moins en mesure de savoir o\u00f9 se trouvent nos donn\u00e9es, qui y a acc\u00e8s, \u00e0 quoi elles servent et surtout, \u00e0 la lumi\u00e8re des cas de violations de donn\u00e9es m\u00e9diatis\u00e9s r\u00e9cemment, de quelle mani\u00e8re elles sont prot\u00e9g\u00e9es par les organisations.<\/p>\n<p>M\u00eame si le gouvernement canadien a r\u00e9agi \u00e0 ces inqui\u00e9tudes en apportant des modifications \u00e0 la\u00a0<em>Loi sur la protection des renseignements personnels et les documents \u00e9lectroniques<\/em>\u00a0(la \u00ab\u00a0LPRPDE\u00a0\u00bb), il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0<strong>R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es<\/strong>\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).<\/p>\n<h3><u>Qu\u2019est-ce que le RGPD?<\/u><\/h3>\n<p>Dans moins d\u2019un an (plus pr\u00e9cis\u00e9ment, le 25\u00a0mai\u00a02018), le cadre de protection des donn\u00e9es de l\u2019Union europ\u00e9enne subira sa plus importante transformation des deux derni\u00e8res d\u00e9cennies. En effet, le RGPD remplacera la Directive sur la protection des donn\u00e9es (la \u00ab\u00a0directive\u00a095\/46\/CE\u00a0\u00bb ou \u00ab\u00a0DPD\u00a0\u00bb) par un nouveau cadre r\u00e9glementaire visant \u00e0 \u00e9tendre les obligations auxquelles sont soumises les organisations qui traitent des renseignements personnels ainsi qu\u2019\u00e0 renforcer le contr\u00f4le des citoyens de l\u2019UE sur la collecte et l\u2019utilisation de leurs renseignements personnels.<\/p>\n<p>Le RGPD pr\u00e9voit que les particuliers ont les droits suivants \u00e0 l\u2019\u00e9gard de leurs renseignements personnels<a name=\"_ftnref1\"><\/a><a href=\"#_ftn1\">[1]<\/a>\u00a0:<\/p>\n<ul>\n<li>le droit \u00e0 l\u2019information;<\/li>\n<li>le droit d\u2019acc\u00e8s aux donn\u00e9es;<\/li>\n<li>le droit de rectification;<\/li>\n<li>le droit \u00e0 l\u2019oubli;<\/li>\n<li>le droit \u00e0 la limitation du traitement;<\/li>\n<li>le droit \u00e0 la portabilit\u00e9 des donn\u00e9es;<\/li>\n<li>le droit d\u2019opposition;<\/li>\n<li>le droit de ne pas faire l\u2019objet d\u2019une d\u00e9cision automatis\u00e9e (y compris du profilage);<\/li>\n<li>le droit d\u2019obtenir une explication quant \u00e0 une d\u00e9cision prise selon une proc\u00e9dure math\u00e9matique.<\/li>\n<\/ul>\n<p>Pour obtenir plus de renseignements sur les r\u00e9percussions de ces droits, consultez\u00a0<a href=\"https:\/\/ico.org.uk\/for-organisations\/data-protection-reform\/overview-of-the-gdpr\/key-areas-to-consider\/\">ce lien<\/a>\u00a0(en anglais seulement).<\/p>\n<h3><u>Pourquoi les propri\u00e9taires d\u2019entreprises canadiens devraient-ils s\u2019int\u00e9resser au RGPD?<\/u><\/h3>\n<p>Le RGPD s\u2019applique \u00e0 toute organisation \u2013 peu importe son lieu de r\u00e9sidence \u2013 qui traite des donn\u00e9es personnelles de r\u00e9sidents ou de citoyens de l\u2019UE. Reposant sur le principe que la \u00ab\u00a0protection des personnes physiques \u00e0 l\u2019\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel est un droit fondamental<a name=\"_ftnref2\"><\/a><a href=\"#_ftn2\">[2]<\/a>\u00a0\u00bb, le RGPD \u00ab\u00a0mettra bient\u00f4t la barre encore plus haut<a name=\"_ftnref3\"><\/a><a href=\"#_ftn3\">[3]<\/a>\u00a0\u00bb pour les organisations canadiennes qui utilisent ou traitent de telles donn\u00e9es.<\/p>\n<p>Pour se conformer au R\u00e8glement, les organisations doivent examiner leurs strat\u00e9gies, leurs politiques et leurs proc\u00e9dures en mati\u00e8re de cybers\u00e9curit\u00e9 et de protection des donn\u00e9es afin de s\u2019assurer qu\u2019elles ont mis en place des sauvegardes et des contr\u00f4les appropri\u00e9s.<\/p>\n<h3><u>RGPD ou DPD \u2013 quelles sont les diff\u00e9rences?<\/u><\/h3>\n<p>Plusieurs changements ou am\u00e9liorations cl\u00e9s changeront fondamentalement notre perception de la confidentialit\u00e9 et de la protection des donn\u00e9es\u00a0:<\/p>\n<h3>Port\u00e9e \u00e9largie<\/h3>\n<p>En plus d\u2019assujettir les organisations qui, sans n\u00e9cessairement exercer des activit\u00e9s dans l\u2019UE, traitent des renseignements de citoyens de l\u2019UE, le RGPD\u00a0:<\/p>\n<ul>\n<li>\u00e9tend la port\u00e9e des renseignements personnels afin d\u2019englober \u00ab\u00a0toute information se rapportant \u00e0 une personne physique identifi\u00e9e ou identifiable<a name=\"_ftnref4\"><\/a><a href=\"#_ftn4\">[4]<\/a>\u00bb, ce qui signifie que des donn\u00e9es peuvent \u00eatre r\u00e9put\u00e9es des renseignements personnels m\u00eame lorsqu\u2019elles ne permettent pas au responsable du traitement d\u2019identifier une personne physique ou qu\u2019elles ont \u00e9t\u00e9 ainsi class\u00e9es;<\/li>\n<li>introduit des dispositions particuli\u00e8res relatives aux \u00ab\u00a0sous-traitants\u00a0\u00bb, soit des organisations qui peuvent traiter des renseignements pour le compte d\u2019une autre organisation et \u00e0 sa demande. Non seulement les sous-traitants devront se conformer aux m\u00eames r\u00e8gles (adopter des sauvegardes appropri\u00e9es, effectuer des analyses d\u2019impact r\u00e9guli\u00e8res, etc.), mais ils seront \u00e9galement assujettis aux m\u00eames sanctions que les responsables du traitement.<\/li>\n<\/ul>\n<h3>Consentement<\/h3>\n<p>En vertu du nouveau R\u00e8glement, le consentement du particulier doit d\u00e9sormais \u00eatre manifest\u00e9 \u00ab\u00a0de fa\u00e7on libre, sp\u00e9cifique, \u00e9clair\u00e9e et univoque<a name=\"_ftnref5\"><\/a><a href=\"#_ftn5\">[5]<\/a>\u00a0\u00bb pour \u00eatre r\u00e9put\u00e9 valide. Le consentement implicite, un \u00e9l\u00e9ment important du domaine canadien de la protection des renseignements personnels, pourrait ne plus \u00eatre acceptable dans certaines circonstances. Le RGPD pr\u00e9voit \u00e9galement des dispositions particuli\u00e8res en ce qui concerne le consentement des enfants (comme l\u2019obtention du consentement de l\u2019autorit\u00e9 parentale).<\/p>\n<h3>Notification d\u2019une violation de donn\u00e9es<\/h3>\n<p>Compte tenu de la possibilit\u00e9 accrue d\u2019une divulgation non autoris\u00e9e des renseignements personnels, le RGPD contient des dispositions tr\u00e8s pr\u00e9cises de notification de toute violation de donn\u00e9es, qui deviendront la norme pour toutes les organisations de l\u2019EU, quel que soit leur emplacement. Le RGPD exige que les organisations et les entreprises<a name=\"_ftnref6\"><\/a><a href=\"#_ftn6\">[6]<\/a>\u00a0:<\/p>\n<ul>\n<li>notifient toute violation des donn\u00e9es \u00e0 leur autorit\u00e9 de contr\u00f4le dans un d\u00e9lai de 72\u00a0heures (lorsque cela est possible);<\/li>\n<li>avisent les particuliers en cas de perte, de vol ou de fraude de leurs renseignements personnels;<\/li>\n<li>tiennent \u00e0 jour un registre de toutes les atteintes \u00e0 la s\u00e9curit\u00e9 des donn\u00e9es et soient capables de fournir ledit registre \u00e0 l\u2019autorit\u00e9 de contr\u00f4le sur demande;<\/li>\n<li>permettent \u00e0 l\u2019autorit\u00e9 de contr\u00f4le d\u2019auditer leurs processus et proc\u00e9dures internes sur demande.<\/li>\n<\/ul>\n<h3><strong><br \/>\n<\/strong>Droit \u00e0 l\u2019oubli<\/h3>\n<p>L\u2019introduction du droit \u00e0 l\u2019effacement, commun\u00e9ment appel\u00e9 le droit \u00e0 l\u2019oubli, repr\u00e9sente une diff\u00e9rence importante entre le DPD et le RGPD. Bien que ce droit puisse \u00eatre exerc\u00e9 dans des certaines circonstances seulement, il offre \u00e0 la personne concern\u00e9e la possibilit\u00e9 de demander la suppression de ses renseignements personnels.<\/p>\n<h3>D\u00e9l\u00e9gu\u00e9s \u00e0 la protection des donn\u00e9es<\/h3>\n<p>Le RGPD exige que les organisations nomment un d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es. Selon le R\u00e8glement, ce dernier est responsable de\u00a0:<\/p>\n<ul>\n<li>surveiller le respect du R\u00e8glement, y compris en ce qui concerne la formation et la sensibilisation du personnel;<\/li>\n<li>fournir des conseils en ce qui concerne les analyses d\u2019impact ou les r\u00e9aliser;<\/li>\n<li>faire office de point de contact pour l\u2019autorit\u00e9 de contr\u00f4le.<\/li>\n<\/ul>\n<h3><strong><br \/>\n<\/strong>Responsabilit\u00e9 et gouvernance<\/h3>\n<p>La responsabilit\u00e9 et la gouvernance sont deux piliers fondamentaux du RGPD. Pour d\u00e9montrer leur niveau de responsabilit\u00e9, on s\u2019attend \u00e0 ce que les organisations puissent produire ce qui suit\u00a0:<\/p>\n<ul>\n<li>des registres d\u00e9taill\u00e9s de toutes leurs activit\u00e9s de traitement;<\/li>\n<li>des preuves des analyses d\u2019impact r\u00e9alis\u00e9es avant le traitement;<\/li>\n<li>des preuves de la mise en \u0153uvre, du test et de l\u2019\u00e9valuation des sauvegardes appropri\u00e9es;<\/li>\n<li>des preuves de la nomination d\u2019un d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (tel qu\u2019il est expliqu\u00e9 ci-dessus);<\/li>\n<li>des registres d\u00e9taill\u00e9s de toute violation de donn\u00e9es, notamment des notifications \u00e0 l\u2019autorit\u00e9 de contr\u00f4le et aux personnes concern\u00e9es.<\/li>\n<\/ul>\n<h3><strong><u><br \/>\n<\/u><\/strong><u>Quel est le risque li\u00e9 \u00e0 la non-conformit\u00e9?<\/u><\/h3>\n<p>Toute organisation qui omet de se conformer au RGPD est passible d\u2019amendes pouvant s\u2019\u00e9lever \u00e0 20\u00a0000\u00a0000\u00a0EUR ou jusqu\u2019\u00e0 4\u00a0% de son chiffre d\u2019affaires annuel mondial (selon le plus \u00e9lev\u00e9 des deux montants) compte tenu du type de violation. De plus, gr\u00e2ce au RGPD, il sera plus facile pour les personnes concern\u00e9es (les particuliers) de d\u00e9poser des r\u00e9clamations contre des responsables du traitement et des sous-traitants. Il va sans dire que toute organisation assujettie au RGPD doit toujours avoir en t\u00eate le RGPD et les risques li\u00e9s aux infractions \u00e0 la cybers\u00e9curit\u00e9.<\/p>\n<h3><u>Comment pouvez-vous vous pr\u00e9parer?<\/u><\/h3>\n<p>Selon la commissaire \u00e0 l\u2019information du Royaume-Uni, Elizabeth\u00a0Denham, \u00ab\u00a0nous devrons tous changer notre fa\u00e7on d\u2019envisager la protection des donn\u00e9es<a name=\"_ftnref7\"><\/a><a href=\"#_ftn7\">[7]<\/a>.\u00a0\u00bb Pour pr\u00e9parer votre organisation en vue de l\u2019entr\u00e9e en vigueur du RGPD, vous devriez<a name=\"_ftnref8\"><\/a><a href=\"#_ftn8\">[8]<\/a>\u00a0:<\/p>\n<ol>\n<li><strong><em><u>Mobiliser <\/u><\/em><\/strong><em><u>les responsables de la s\u00e9curit\u00e9 et de la protection des renseignements personnels de votre organisation<br \/>\n<\/u><\/em>Ces personnes joueront un r\u00f4le essentiel en soutenant votre organisation dans l\u2019\u00e9tablissement de sa strat\u00e9gie g\u00e9n\u00e9rale de conformit\u00e9 et de son cadre de responsabilisation ainsi que dans la d\u00e9termination des lacunes li\u00e9es \u00e0 s\u00e9curit\u00e9 et \u00e0 la protection des renseignements personnels au sein de vos processus existants. En outre, ces personnes peuvent vous aider \u00e0 identifier votre autorit\u00e9 de contr\u00f4le conform\u00e9ment au RGPD et elles pourraient agir en tant que d\u00e9l\u00e9gu\u00e9es \u00e0 la protection des donn\u00e9es ou apporter leur aide \u00e0 la personne ainsi nomm\u00e9e. Si votre organisation ne compte pas d\u00e9j\u00e0 de telles personnes au sein de ses rangs, trouvez un conseiller de confiance qui poss\u00e8de ces comp\u00e9tences. Amorcer la conversation t\u00f4t dans le processus peut vous aider \u00e0 \u00eatre s\u00fbr que vous \u00eates sur la bonne voie.<\/li>\n<li><strong><em><u>Identifier <\/u><\/em><\/strong><em><u>et classer les donn\u00e9es confidentielles<br \/>\n<\/u><\/em>Comprendre vos donn\u00e9es est une premi\u00e8re \u00e9tape essentielle \u00e0 leur protection. Ce n\u2019est qu\u2019apr\u00e8s avoir identifi\u00e9 et class\u00e9 de telles donn\u00e9es que votre organisation peut \u00e9valuer l\u2019applicabilit\u00e9 du R\u00e8glement (c.-\u00e0-d. traitez-vous des renseignements d\u2019identification personnels de citoyens de l\u2019UE?), d\u00e9terminer les exigences en mati\u00e8re de protection des donn\u00e9es que vous conservez et \u00e9tablir le plan de r\u00e9ponse appropri\u00e9 en cas de compromission desdits renseignements. Il est \u00e9galement recommand\u00e9, lorsque cela est possible, de rendre anonymes les renseignements confidentiels que l\u2019organisation d\u00e9tient afin de r\u00e9duire les risques.<\/li>\n<li><strong><em><u>Revoir <\/u><\/em><\/strong><em><u>les politiques, les processus et les proc\u00e9dures<br \/>\n<\/u><\/em>Votre organisation doit revoir ses politiques, \u00e9nonc\u00e9s et proc\u00e9dures actuels relatifs \u00e0 la confidentialit\u00e9, \u00e0 la s\u00e9curit\u00e9 et au traitement des donn\u00e9es afin d\u2019assurer le respect aux exigences du R\u00e8glement (notamment le traitement des demandes d\u2019acc\u00e8s, l\u2019identification de la base l\u00e9gale de l\u2019organisation aux fins du traitement, l\u2019obtention des consentements n\u00e9cessaires, la notification des violations, etc.). La mise en \u0153uvre de politiques et de plans efficaces relatifs aux atteintes \u00e0 la vie priv\u00e9e et \u00e0 la protection des renseignements personnels permet \u00e0 votre organisation de se conformer \u00e0 ses (nouvelles) exigences l\u00e9gales, tout en att\u00e9nuant le risque global.<\/li>\n<li><strong><em><u>R\u00e9aliser <\/u><\/em><\/strong><em><u>des \u00e9valuations des facteurs relatifs \u00e0 la vie priv\u00e9e<\/u><\/em>Les \u00e9valuations des facteurs relatifs \u00e0 la vie priv\u00e9e peuvent aider votre organisation \u00e0 comprendre a)\u00a0quels sont les renseignements personnels qu\u2019elle conserve; b)\u00a0pourquoi ces renseignements sont recueillis et c)\u00a0de quelle fa\u00e7on ces renseignements seront recueillis, trait\u00e9s et enregistr\u00e9s. Proc\u00e9der \u00e0 une \u00e9valuation des facteurs relatifs \u00e0 la vie priv\u00e9e permet de r\u00e9duire les risques relatifs \u00e0 la confidentialit\u00e9 des donn\u00e9es qui peuvent survenir dans le cadre des op\u00e9rations quotidiennes de votre entreprise et de d\u00e9montrer que toutes les pr\u00e9cautions raisonnables d\u2019un point de vue commercial ont \u00e9t\u00e9 prises dans le but de prot\u00e9ger les renseignements personnels en votre possession. Envisagez \u00e9galement d\u2019incorporer la Protection int\u00e9gr\u00e9e de la vie priv\u00e9e<a name=\"_ftnref9\"><\/a><a href=\"#_ftn9\">[9]<\/a>\u00a0\u00e0 vos activit\u00e9s quotidiennes afin de pr\u00e9venir de mani\u00e8re proactive tout incident d\u2019atteinte \u00e0 la vie priv\u00e9e au sein de l\u2019organisation.<\/li>\n<li><strong><em><u>\u00c9valuer <\/u><\/em><\/strong><em><u>les fournisseurs de services<br \/>\n<\/u><\/em>Votre organisation doit passer en revue ses fournisseurs de services actuels. \u00c9tant donn\u00e9 que \u00ab\u00a0le degr\u00e9 de cybers\u00e9curit\u00e9 d\u2019une entreprise d\u00e9pend de celui de ses fournisseurs<a name=\"_ftnref10\"><\/a><a href=\"#_ftn10\">[10]<\/a>\u00a0\u00bb, il est essentiel de d\u00e9terminer si l\u2019un d\u2019entre eux comporte un niveau de risque inacceptable \u00e0 cause d\u2019un manque de contr\u00f4les, de politiques ou de proc\u00e9dures de s\u00e9curit\u00e9. Il est \u00e9galement conseill\u00e9 de revoir vos proc\u00e9dures d\u2019approvisionnement et d\u2019incorporer les exigences de cybers\u00e9curit\u00e9 et de protection des donn\u00e9es \u00e0 votre processus de s\u00e9lection et aux contrats de service \u00e0 venir. Pour les fournisseurs actuels, il est fortement recommand\u00e9 de modifier les ententes en vigueur afin de refl\u00e9ter les nouvelles exigences r\u00e9glementaires.<\/li>\n<li><strong><em><u>Mettre en \u0153uvre <\/u><\/em><\/strong><em><u>un programme de formation en mati\u00e8re de sensibilisation \u00e0 la s\u00e9curit\u00e9 et \u00e0 la protection des donn\u00e9es<br \/>\n<\/u><\/em>Vous devez planifier des ateliers d\u2019information et fournir aux membres des \u00e9quipes les documents de r\u00e9f\u00e9rence et le mat\u00e9riel de formation appropri\u00e9s. Les employ\u00e9s jouent un r\u00f4le essentiel lorsque vient le temps d\u2019assurer la protection de votre entreprise et de vos donn\u00e9es. Non seulement ils doivent recevoir la formation ad\u00e9quate sur la fa\u00e7on de recueillir, de traiter et d\u2019enregistrer les donn\u00e9es conform\u00e9ment au R\u00e8glement (et afin d\u2019emp\u00eacher les violations de donn\u00e9es), mais ils doivent \u00e9galement savoir comment identifier les \u00e9ventuelles violations et en faire \u00e9tat. Ils repr\u00e9sentent votre premi\u00e8re ligne de d\u00e9fense.<\/li>\n<li><strong><em><u>Envisager <\/u><\/em><\/strong><em><u>les solutions de gestion des informations et \u00e9v\u00e9nements de s\u00e9curit\u00e9<br \/>\n<\/u><\/em>Les outils SIEM (Security Information and Event Management) prennent en charge\u00a0la d\u00e9tection des menaces et la r\u00e9ponse aux incidents \u00e0 l\u2019aide de la collecte et de l\u2019analyse en temps r\u00e9el des \u00e9v\u00e9nements li\u00e9s \u00e0 la s\u00e9curit\u00e9 ainsi que la production des rapports de conformit\u00e9. \u00c9tant\u00a0donn\u00e9 que le R\u00e8glement exige que les organisations tiennent \u00e0 jour un registre de toutes les violations,\u00a0il serait judicieux qu\u2019elles \u00e9laborent leurs propres solutions technologiques ou aient recours aux services d\u2019un tiers afin de les appuyer dans leurs efforts de d\u00e9tection et de conformit\u00e9.<\/li>\n<\/ol>\n<h3><u>Comment Richter peut-il vous aider?<\/u><\/h3>\n<p>Il n\u2019est pas trop tard! Notre feuille de route sur la conformit\u00e9 au RGPD ci-dessous illustre les t\u00e2ches que votre organisation devrait effectuer afin de se conformer au RGPD. Le calendrier est pr\u00e9sent\u00e9 \u00e0 titre indicatif seulement, et nous pouvons aider votre organisation \u00e0 accomplir ces t\u00e2ches pour qu\u2019elle soit conforme au R\u00e8glement au moment voulu.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5478 size-full\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/tableau-fr.png\" alt=\"Conformit\u00e9 RGPD, les \u00e9tapes n\u00e9cessaire que les entreprises doivent respecter afin d'\u00eatre conforme aux \u00e9xigences\" width=\"989\" height=\"535\" srcset=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/tableau-fr.png 989w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/tableau-fr-600x325.png 600w, https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/09\/tableau-fr-768x415.png 768w\" sizes=\"auto, (max-width: 989px) 100vw, 989px\" \/><\/p>\n<p>Chez Richter, nous avons une \u00e9quipe de professionnels qui poss\u00e8dent l\u2019expertise appropri\u00e9e pour r\u00e9pondre aux besoins de votre organisation. Nous confierons les mandats \u00e0 des membres de l\u2019\u00e9quipe qui s\u2019engageront \u00e0 vous offrir des solutions conformes \u00e0 vos attentes en mati\u00e8re de qualit\u00e9 \u00e9lev\u00e9e. Nos professionnels sont titulaires de titres professionnels pertinents, dont les suivants\u00a0:<\/p>\n<ul>\n<li><strong>Certified Information Systems Security Professional (CISSP)<\/strong><\/li>\n<li><strong>Certified Information Security Manager (CISM);<\/strong><\/li>\n<li><strong>Certified Information Privacy Professional (CIPP).<\/strong><\/li>\n<li><strong>Certified in Risk and Information Systems Control (CRISC);<\/strong><\/li>\n<li><strong>Certified Cloud Security Professional (CCSP)<\/strong><\/li>\n<li><strong>Certified Information Systems Auditor (CISA)<\/strong><\/li>\n<li><strong>Comptable professionnel agr\u00e9\u00e9 (CPA, CMA), 2001<\/strong><\/li>\n<li><strong>Certified Internal\u00a0Auditor (CIA);\u00a0<\/strong><\/li>\n<\/ul>\n<h3><u>Au sujet de Richter<\/u><\/h3>\n<p><em>Richter, qui a \u00e9t\u00e9 fond\u00e9 \u00e0 Montr\u00e9al en 1926, est un cabinet comptable autoris\u00e9 qui offre des services de certification, de fiscalit\u00e9 et de gestion de patrimoine, ainsi que des services-conseils financiers dans les domaines de la restructuration organisationnelle, des op\u00e9rations et de l\u2019insolvabilit\u00e9, de l\u2019\u00e9valuation et du financement d\u2019entreprises, du soutien en mati\u00e8re de litiges financiers, de la gestion des risques et de la cybers\u00e9curit\u00e9, et de la juricomptabilit\u00e9. Notre engagement envers l\u2019excellence, notre compr\u00e9hension approfondie des enjeux financiers et nos m\u00e9thodes pratiques de r\u00e9solution de probl\u00e8mes nous ont permis de devenir l\u2019un des plus importants cabinets ind\u00e9pendants d\u2019expertise comptable, de services-conseils organisationnels et de consultation au pays. Richter a des bureaux \u00e0 Toronto et \u00e0 Montr\u00e9al. Vous pouvez nous suivre<\/em>\u00a0sur\u00a0<a href=\"http:\/\/www.linkedin.com\/company\/richter?trk=hb_tab_compy_id_255303\"><em>LinkedIn<\/em><\/a><em>,<\/em>\u00a0<a href=\"http:\/\/www.facebook.com\/pages\/Richter\/86042934738\"><em>Facebook<\/em><\/a>\u00a0<em>ou<\/em>\u00a0<a href=\"https:\/\/twitter.com\/Richtercanada\"><em>Twitter<\/em><\/a>.<\/p>\n<p><a name=\"_ftn1\"><\/a><a href=\"#_ftnref1\">[1]<\/a>\u00a0<a href=\"https:\/\/ico.org.uk\/for-organisations\/data-protection-reform\/overview-of-the-gdpr\/key-areas-to-consider\/\">https:\/\/ico.org.uk\/for-organisations\/data-protection-reform\/overview-of-the-gdpr\/key-areas-to-consider\/<\/a><\/p>\n<p><a name=\"_ftn2\"><\/a><a href=\"#_ftnref2\">[2]<\/a>\u00a0<a href=\"http:\/\/ec.europa.eu\/justice\/data-protection\/reform\/files\/regulation_oj_en.pdf\">http:\/\/ec.europa.eu\/justice\/data-protection\/reform\/files\/regulation_oj_en.pdf<\/a><\/p>\n<p><a name=\"_ftn3\"><\/a><a href=\"#_ftnref3\">[3]<\/a>\u00a0<a href=\"https:\/\/www.priv.gc.ca\/fr\/nouvelles-du-commissariat\/allocutions\/2016\/sp-d_20160705\/\">https:\/\/www.priv.gc.ca\/fr\/nouvelles-du-commissariat\/allocutions\/2016\/sp-d_20160705\/<\/a><\/p>\n<p><a name=\"_ftn4\"><\/a><a href=\"#_ftnref4\">[4]<\/a>\u00a0<a href=\"http:\/\/ec.europa.eu\/justice\/data-protection\/reform\/files\/regulation_oj_en.pdf\">http:\/\/ec.europa.eu\/justice\/data-protection\/reform\/files\/regulation_oj_en.pdf<\/a><\/p>\n<p><a name=\"_ftn5\"><\/a><a href=\"#_ftnref5\">[5]<\/a>\u00a0Ibid.<\/p>\n<p><a name=\"_ftn6\"><\/a><a href=\"#_ftnref6\">[6]<\/a>\u00a0Ibid.<\/p>\n<p><a name=\"_ftn7\"><\/a><a href=\"#_ftnref7\">[7]<\/a>\u00a0Citation de Elizabeth\u00a0Denham, commissaire \u00e0 l\u2019information, ICO [traduction libre].<\/p>\n<p><a name=\"_ftn8\"><\/a><a href=\"#_ftnref8\">[8]<\/a>\u00a0<a href=\"https:\/\/ico.org.uk\/media\/1624219\/preparing-for-the-gdpr-12-steps.pdf\">https:\/\/ico.org.uk\/media\/1624219\/preparing-for-the-gdpr-12-steps.pdf<\/a><\/p>\n<p><a name=\"_ftn9\"><\/a><a href=\"#_ftnref9\">[9]<\/a>\u00a0<a href=\"https:\/\/www.ipc.on.ca\/wp-content\/uploads\/Resources\/7foundationalprinciples.pdf\">https:\/\/www.ipc.on.ca\/wp-content\/uploads\/Resources\/7foundationalprinciples.pdf<\/a><\/p>\n<p><a name=\"_ftn10\"><\/a><a href=\"#_ftnref10\">[10]<\/a>\u00a0<a href=\"http:\/\/www.reuters.com\/article\/us-regulator-cybersecurity-lawsky-idUSKCN0IB03220141022\">http:\/\/www.reuters.com\/article\/us-regulator-cybersecurity-lawsky-idUSKCN0IB03220141022<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Toutefois, en raison de cet acc\u00e8s sans pr\u00e9c\u00e9dent, nous sommes de moins en moins en mesure de savoir o\u00f9 se trouvent nos donn\u00e9es, qui y a acc\u00e8s, \u00e0 quoi elles servent et surtout, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1371],"class_list":["post-5477","insights","type-insights","status-publish","hentry","insights-type-optimiser-vos-activites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter<\/title>\n<meta name=\"description\" content=\"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter\" \/>\n<meta property=\"og:description\" content=\"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T16:38:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/09\/tableau-fr.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/\",\"name\":\"Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/tableau-fr.png\",\"datePublished\":\"2018-09-19T14:31:08+00:00\",\"dateModified\":\"2021-08-02T16:38:02+00:00\",\"description\":\"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/tableau-fr.png\",\"contentUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/tableau-fr.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le RGPD : changer notre vision de la protection des donn\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter","description":"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter","og_description":"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-08-02T16:38:02+00:00","og_image":[{"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2018\/09\/tableau-fr.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/","name":"Le RGPD : changer notre vision de la protection des donn\u00e9es - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/09\/tableau-fr.png","datePublished":"2018-09-19T14:31:08+00:00","dateModified":"2021-08-02T16:38:02+00:00","description":"Mois de la cybers\u00e9curit\u00e9, Octobre 2017 Nous vivons dans un monde num\u00e9rique, o\u00f9 l\u2019acc\u00e8s \u00e0 l\u2019information est omnipr\u00e9sent dans nos vies quotidiennes. Il est crucial que les propri\u00e9taires d\u2019entreprises canadiens se familiarisent avec les changements r\u00e9glementaires importants qui se pr\u00e9parent outre-mer et pourraient avoir une incidence sur leurs affaires, notamment le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(le \u00ab\u00a0RGPD\u00a0\u00bb ou le \u00ab\u00a0R\u00e8glement\u00a0\u00bb) de l\u2019Union europ\u00e9enne (\u00ab\u00a0UE\u00a0\u00bb).","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/#primaryimage","url":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/09\/tableau-fr.png","contentUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2018\/09\/tableau-fr.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/le-rgpd-changer-notre-vision-de-la-protection-des-donnees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Le RGPD : changer notre vision de la protection des donn\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/5477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=5477"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=5477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}