{"id":5543,"date":"2018-09-19T17:49:38","date_gmt":"2018-09-19T15:49:38","guid":{"rendered":"https:\/\/www.richter.ca\/?p=5543"},"modified":"2021-08-02T17:19:27","modified_gmt":"2021-08-02T15:19:27","slug":"survivre-a-la-paperasse","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/","title":{"rendered":"Survivre \u00e0 la paperasse"},"content":{"rendered":"<p>Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.\u00a0Ce prix doit \u00eatre \u00e9tabli en fonction de renseignements r\u00e9alistes. Mais comment l\u2019acheteur peut-il en \u00eatre vraiment certain? Quelles mesures doivent \u00eatre prises pour obtenir l\u2019heure juste? Quelles d\u00e9marches peuvent\u00a0<em>garantir<\/em>\u00a0le caract\u00e8re raisonnable du contr\u00f4le diligent effectu\u00e9 par l\u2019acheteur et \u00e9viter les conflits d\u00e9sagr\u00e9ables pouvant survenir lorsque les donn\u00e9es \u00ab\u00a0r\u00e9elles\u00a0\u00bb sont d\u00e9voil\u00e9es?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10760\" src=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg\" alt=\"Des gens d'affaires qui discutent d'un plan de transition\" width=\"920\" height=\"483\" \/><\/p>\n<p>En soumettant votre entreprise \u00e0 un contr\u00f4le diligent ad\u00e9quat, vous \u00e9conomiserez du temps et des efforts, en plus d&rsquo;assurer la conclusion d\u2019une entente fond\u00e9e sur des renseignements valables et exacts.<\/p>\n<blockquote>\n<h2>\u00ab En soumettant votre entreprise \u00e0 un contr\u00f4le diligent ad\u00e9quat, vous \u00e9conomiserez du temps et des efforts.\u00a0\u00bb<\/h2>\n<\/blockquote>\n<p>D\u2019une certaine mani\u00e8re, les principes d\u2019un contr\u00f4le diligent sont semblables \u00e0 ceux d\u2019un audit, m\u00eame s\u2019il s\u2019agit de missions r\u00e9solument distinctes. Il faut faire des tests, la revue d\u2019informations cl\u00e9s et de nouveaux calculs.<\/p>\n<h2 style=\"font-size: 30px;\">En g\u00e9n\u00e9ral, ils se concentrent sur certains secteurs, dont les dix principaux sont les suivants :<\/h2>\n<ol>\n<li>le dossier fiscal\u00a0: la nature et la fr\u00e9quence des nouvelles cotisations;<\/li>\n<li>une comptabilit\u00e9 audacieuse, tout particuli\u00e8rement en ce qui concerne la sur\u00e9valuation des actifs ou le d\u00e9faut de comptabiliser tous les passifs;<\/li>\n<li>des stocks d\u00e9suets qui n\u00e9cessitent une r\u00e9duction de valeur (situation fr\u00e9quente dans plusieurs entreprises; un poste important du bilan);<\/li>\n<li>des op\u00e9rations avec lien de d\u00e9pendance (avec des membres de la parent\u00e9 ou le propri\u00e9taire, \u00e0 qui un salaire n\u2019a peut-\u00eatre pas \u00e9t\u00e9 vers\u00e9, mais plut\u00f4t des dividendes);<\/li>\n<li>des d\u00e9penses discr\u00e9tionnaires \u00e9lev\u00e9es;<\/li>\n<li>des exigences en mati\u00e8re de production de d\u00e9clarations de revenus aux \u00c9tats-Unis ou autres \u00e0 satisfaire;<\/li>\n<li>l\u2019identit\u00e9 et la fonction des personnes dont le nom figure sur la liste de paie; l\u2019\u00e9tat de la situation financi\u00e8re de l\u2019entreprise, apr\u00e8s ajustements, si des membres de la famille devaient \u00eatre remplac\u00e9s;<\/li>\n<li>des r\u00e9ductions des d\u00e9penses en R&amp;D en pr\u00e9vision de la vente;<\/li>\n<li>une sous-\u00e9valuation des produits d\u00e9coulant de d\u00e9penses discr\u00e9tionnaires d\u2019une soci\u00e9t\u00e9 ferm\u00e9e (ou au moins la d\u00e9claration du vendeur \u00e0 cet \u00e9gard);<\/li>\n<li>une sur\u00e9valuation des produits compte tenu des r\u00e9ductions de d\u00e9penses effectu\u00e9es avant la vente, ce qui peut avoir des cons\u00e9quences sur la rentabilit\u00e9 future de l\u2019entreprise.<\/li>\n<\/ol>\n<p>Le contr\u00f4le diligent comptable fait partie int\u00e9grante de la r\u00e9ussite de tout processus de fusion et d\u2019acquisition. Lorsque la valeur d\u2019une entreprise est \u00e9tablie avec exactitude et que toutes les parties sont satisfaites, le processus d\u2019achat a beaucoup plus de chances d\u2019\u00eatre couronn\u00e9 de succ\u00e8s.<\/p>\n<h2><span style=\"font-size: 30px;\">Comment nous pouvons vous aider<\/span><\/h2>\n<p>Nous disons vrai lorsque nous qualifions notre approche d\u2019holistique. Car celle-ci gravite autour de vous. Nous ne pensons pas qu\u2019\u00e0 votre entreprise ou \u00e0 votre h\u00e9ritage\u00a0: nous pensons \u00e0 vous avant tout. Nos services-conseils aux propri\u00e9taires d\u2019entreprises et \u00e0 leur famille concernent aussi bien l\u2019aspect professionnel que personnel. Nos professionnels (notamment en gestion de patrimoine, en \u00e9valuation d\u2019entreprises, en fiscalit\u00e9, en successions et en une foule d\u2019autres gammes de services) unissent leurs efforts pour vous offrir des conseils qui conviennent \u00e0 votre situation et \u00e0 vos objectifs, car votre travail a une incidence sur votre vie personnelle, et vice versa \u2013 l\u2019un ne va pas sans l\u2019autre. Gr\u00e2ce \u00e0 une planification pr\u00e9coce et exhaustive, nos professionnels \u00e9valuent chaque cas et proposent des options afin que vous puissiez prendre des d\u00e9cisions \u00e9clair\u00e9es et strat\u00e9giques pour tirer le maximum de votre propre situation.<\/p>\n<h3>Lisez d&rsquo;autres articles sur la planification d&rsquo;une transition d&rsquo;entreprise :<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/la-transparence-est-la-cle\/\">La transparence est la cl\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/www.richter.ca\/fr\/visualiser-pour-mieux-planifier\/\">Visualiser pour mieux planifier<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.\u00a0Ce prix doit \u00eatre \u00e9tabli en fonction de renseignements r\u00e9alistes. Mais comment l\u2019acheteur peut-il en \u00eatre vraiment certain? Quelles mesures doivent [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1356],"class_list":["post-5543","insights","type-insights","status-publish","hentry","insights-type-planification-de-la-transition-et-de-la-succession"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Survivre \u00e0 la paperasse - Richter<\/title>\n<meta name=\"description\" content=\"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Survivre \u00e0 la paperasse - Richter\" \/>\n<meta property=\"og:description\" content=\"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T15:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/\",\"name\":\"Survivre \u00e0 la paperasse - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/transition_series_photo_600x315px.jpg\",\"datePublished\":\"2018-09-19T15:49:38+00:00\",\"dateModified\":\"2021-08-02T15:19:27+00:00\",\"description\":\"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/transition_series_photo_600x315px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.richter.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/transition_series_photo_600x315px.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/survivre-a-la-paperasse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Survivre \u00e0 la paperasse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Survivre \u00e0 la paperasse - Richter","description":"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Survivre \u00e0 la paperasse - Richter","og_description":"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2021-08-02T15:19:27+00:00","og_image":[{"url":"https:\/\/www.www.richter.ca\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/","name":"Survivre \u00e0 la paperasse - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/#primaryimage"},"image":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg","datePublished":"2018-09-19T15:49:38+00:00","dateModified":"2021-08-02T15:19:27+00:00","description":"Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de Avant de vous lancer \u00e0 la recherche d\u2019un acheteur admissible, il est important de faire certaines d\u00e9clarations \u00e0 l\u2019\u00e9gard de la situation financi\u00e8re de votre entreprise afin de justifier le prix que vous esp\u00e9rez obtenir.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/#primaryimage","url":"https:\/\/www.richter.ca\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg","contentUrl":"https:\/\/www.richter.ca\/wp-content\/uploads\/2019\/11\/transition_series_photo_600x315px.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/survivre-a-la-paperasse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Survivre \u00e0 la paperasse"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/5543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=5543"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=5543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}