{"id":6061,"date":"2018-10-11T21:43:59","date_gmt":"2018-10-11T19:43:59","guid":{"rendered":"https:\/\/www.richter.ca\/?p=6061"},"modified":"2023-02-06T16:52:47","modified_gmt":"2023-02-06T15:52:47","slug":"protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/","title":{"rendered":"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation"},"content":{"rendered":"<p><em>par Groupe services-conseils en gestion des risques <\/em><\/p>\n<p><em>Original, tel qu\u2019il appara\u00eet sur Finance et Investissement &#8211; <\/em><a href=\"https:\/\/www.finance-investissement.com\/\"><em>https:\/\/www.finance-investissement.com\/<\/em><\/a><\/p>\n<p><em>La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<h2 style=\"font-size: 30px;\">Vous ne savez pas de quoi je parle ? Je parle des demandes de consentement li\u00e9 \u00e0 vos donn\u00e9es personnelles (PII) que vous recevez ici et l\u00e0 de vos sites web pr\u00e9f\u00e9r\u00e9s. Beaucoup m\u2019ont demand\u00e9 : \u00ab Comment peut-on g\u00e9rer autant de r\u00e8glementation? \u00bb.<\/h2>\n<h3>Revenir \u00e0 la base !<\/h3>\n<p>Le risque d\u2019\u00eatre non conforme existe depuis la cr\u00e9ation des lois. Par exemple, \u00e0 l\u2019\u00e9poque de Mo\u00efse, si les gens ne se conformaient pas aux 10 commandements (le D\u00e9calogue), ils risquaient les \u00abfoudres\u00bb th\u00e9istes ou de ne pas acc\u00e9der au paradis une fois notre derni\u00e8re heure venue, tout d\u00e9pend (ou pas) des croyances de chacun. Il en est de m\u00eame pour la GDPR, la Norme de s\u00e9curit\u00e9 de l\u2019industrie des cartes de paiment (PCI) ou la Health Insurance Portability and Accountability Act (HIPAA), il est possible de prendre le risque d\u2019\u00eatre non conforme.<\/p>\n<p>Il n\u2019y a que quatre mani\u00e8res de g\u00e9rer ce type de risque : l\u2019accepter et risquer la sanction, le mitiger\/r\u00e9duire et investir temps ou argent pour implanter un contr\u00f4le, le transf\u00e9rer et prendre une assurance par exemple (dans le cas de la r\u00e8glementation, il est rare qu\u2019un assureur accepte de vous assurer contre le non-respect de la loi ou sinon la prime sera sal\u00e9e) et enfin l\u2019annuler.<\/p>\n<p>Oui, il est possible d\u2019annuler un risque. Dans le cas du risque d\u2019\u00eatre non conforme, l\u2019annulation est la meilleure solution, ou du moins la plus efficace et la moins co\u00fbteuse \u00e0 long terme.<\/p>\n<h3>Annuler un risque<\/h3>\n<p>Un risque est une perte potentielle d\u2019une qualit\u00e9 (disponibilit\u00e9, confidentialit\u00e9, int\u00e9grit\u00e9, flexibilit\u00e9, mobilit\u00e9\u2026etc.) d\u2019un actif, li\u00e9e \u00e0 l\u2019impact d\u00fb \u00e0 l\u2019exposition (via une d\u00e9faillance, par exemple) de cet actif \u00e0 un agent de menace. En clair, dans le cas d\u2019un incendie r\u00e9sidentiel : l\u2019actif c\u2019est la maison et son contenu, la menace c\u2019est l\u2019huile sur le feu, l\u2019exposition (la d\u00e9faillance) est l\u2019absence de surveillance de cette casserole d\u2019huile par un adulte responsable. Donc, l\u2019annulation s\u2019op\u00e8re par la suppression de l\u2019actif : la maison par exemple. Si vous n\u2019avez pas de maison, vous n\u2019avez ainsi aucune exposition \u00e0 la menace et \u00e0 son impact potentiel.<\/p>\n<p>Je vois que vous commencez \u00e0 comprendre o\u00f9 je vous emm\u00e8ne et j\u2019entends d\u00e9j\u00e0 certains d\u2019entre vous me dire que cette solution n\u2019est tout simplement pas applicable car trop extr\u00eame. Eh bien, prenez le temps de r\u00e9fl\u00e9chir \u00e0 cette option, parce qu\u2019elle est viable.<\/p>\n<p>La majorit\u00e9 des \u00e9cosyst\u00e8mes de donn\u00e9es ayant oblig\u00e9 les entreprises \u00e0 la conformit\u00e9 sont souvent des donn\u00e9es non-capitalisables et inutiles du processus d\u2019affaires r\u00e9el. Nous n\u2019avons juste pas appris \u00e0 ne pas les collecter.<\/p>\n<p>En effet, la d\u00e9mat\u00e9rialisation de l\u2019information, la facilit\u00e9 et l\u2019augmentation des espaces de stockage informatique nous ont cr\u00e9\u00e9 des travers de \u00abboulimie d\u2019information\u00bb.<\/p>\n<p>Nous collectons trop d\u2019informations.<\/p>\n<p>Par exemple, est-ce que les banques ont besoin de votre num\u00e9ro d\u2019assurance sociale ? La r\u00e9ponse est non, pourquoi le demandent-elles ? Par boulimie d\u2019informations. Cette information n\u2019est pas r\u00e9ellement capitalisable et sa collecte ne pr\u00e9sente qu\u2019un risque de perte ou de vol suppl\u00e9mentaire de cette information pr\u00e9cieuse.<\/p>\n<p>Selon l\u2019\u00e9tude annuelle du Ponemon Institute, une donn\u00e9e au Canada vaut plus de 250$ en cas de perte ou vol, chaque information collect\u00e9e sur un individu s\u2019additionnant.<\/p>\n<p>Plus votre dossier d\u2019informations sur un m\u00eame individu grossi (client, partenaire ou employ\u00e9), plus le co\u00fbt global du dit dossier augmente.<\/p>\n<p>Ainsi, si vous collectez 20 types d\u2019informations diff\u00e9rentes identifiables sur un m\u00eame individu, ce dossier vous co\u00fbtera plus de 5000$ en cas de perte ou vol. Combien avez d\u2019employ\u00e9s ou de clients ?<\/p>\n<p>Donc, moins vous collectez de donn\u00e9es inutiles, moins vous devez vous conformer \u00e0 des r\u00e8gles contraignantes, et moins lourde sera la facture quand la br\u00e8che arrivera. Le r\u00e8glement GDPR donne aux citoyens europ\u00e9ens le droit de r\u00e9clamer \u00e0 toute entreprise le consentement \u00abexplicite\u00bb et \u00abpositif\u00bb, le droit \u00e0 l\u2019effacement, le droit de recevoir les donn\u00e9es \u00e0 caract\u00e8res personnelles les concernant qu\u2019ils ont fournies, le droit de ne pas faire l\u2019objet d\u2019une d\u00e9cision fond\u00e9e exclusivement sur un traitement automatis\u00e9, y compris le profilage, et le droit d\u2019\u00eatre notifi\u00e9s, d\u00e8s que possible, en cas de violations graves de donn\u00e9es. PCI est la r\u00e8glementation du consortium VISA, MASTERCARD, DISCOVER, JCB et AMEX pour la protection des donn\u00e9es de cartes de paiement et HIPAA s\u2019applique aux citoyens am\u00e9ricains dans le cadre de la protection de leurs donn\u00e9es de sant\u00e9 et d\u2019assurance.<\/p>\n<p>Rappelez-vous que noter une information r\u00e8glement\u00e9e sur un morceau de papier est une collecte d\u2019information \u00e0 part enti\u00e8re.<\/p>\n<p>La solution est de d\u00e9buter l\u2019analyse de votre processus de collecte d\u2019information afin de le rationaliser. Si vous n\u2019avez pas besoin d\u2019une information, ne la collectez pas. Ne tentez pas de g\u00e9rer les cas d\u2019exceptions ou les \u00abOn en aura besoin si \u00e7a arrive\u2026\u00bb, car cela vous poussera \u00e0 collecter de l\u2019information potentiellement r\u00e8glement\u00e9e et inutile pour votre processus d\u2019affaires. Vous devez avoir un Mind Chart ou une architecture des informations r\u00e8glement\u00e9es de tiers (qui ne vous appartiennent pas) dont vous disposez et que vous avez \u00e0 prot\u00e9ger. Diminuez votre responsabilit\u00e9 l\u00e9gale et de s\u00e9curit\u00e9 en limitant le volume de la collecte d\u2019information et en rationnalisant son traitement. Ce faisant, vous limiterez \u00e9galement l\u2019int\u00e9r\u00eat des cybercriminels \u00e0 votre \u00e9gard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement &#8211; https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1362],"class_list":["post-6061","insights","type-insights","status-publish","hentry","insights-type-assurer-la-cybersecurite-de-votre-entreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter<\/title>\n<meta name=\"description\" content=\"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter\" \/>\n<meta property=\"og:description\" content=\"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T15:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\\\/\",\"name\":\"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2018-10-11T19:43:59+00:00\",\"dateModified\":\"2023-02-06T15:52:47+00:00\",\"description\":\"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\\\/\\\/www.finance-investissement.com\\\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter","description":"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter","og_description":"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2023-02-06T15:52:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/","name":"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2018-10-11T19:43:59+00:00","dateModified":"2023-02-06T15:52:47+00:00","description":"par Groupe services-conseils en gestion des risques Original, tel qu\u2019il appara\u00eet sur Finance et Investissement - https:\/\/www.finance-investissement.com\/ La nouvelle Loi europ\u00e9enne sur la protection des donn\u00e9es (GDPR) s\u2019applique depuis le 25 mai. En pr\u00e9vision de son application, plusieurs plaintes ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9pos\u00e9es contre Facebook et Google et plusieurs sites d\u2019information am\u00e9ricains ont carr\u00e9ment interdit l\u2019acc\u00e8s \u00e0 leur site Internet aux internautes europ\u00e9ens.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/protection-des-donnees-une-solution-de-securite-efficace-a-un-surplus-de-reglementation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Protection des donn\u00e9es : une solution de s\u00e9curit\u00e9 efficace \u00e0 un surplus de r\u00e9glementation"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/6061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=6061"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=6061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}