{"id":9666,"date":"2019-06-19T18:25:37","date_gmt":"2019-06-19T16:25:37","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=medianews&#038;p=9666"},"modified":"2020-06-01T23:53:08","modified_gmt":"2020-06-01T21:53:08","slug":"femmes-et-immobilier-la-partie-nest-pas-encore-gagnee","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/","title":{"rendered":"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier"},"content":{"rendered":"<p><em>Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine <\/em>Premi\u00e8res en affaires<em>.<\/em><\/p>\n<h2>L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.<\/h2>\n<p>De la construction aux fonds d\u2019investissement, en passant par les communications et la gestion, elles font leur place, mais la partie est loin d\u2019\u00eatre gagn\u00e9e. Que reste-t-il \u00e0 faire pour que les hommes et les femmes se partagent \u00e9quitablement les r\u00f4les en immobilier? <em>Premi\u00e8res en affaires<\/em> a pos\u00e9 la question \u00e0 celles qui sont aux premi\u00e8res loges.<\/p>\n<p>Les diff\u00e9rentes \u00e9tudes qui se penchent sur la pr\u00e9sence des femmes dans l\u2019immobilier d\u00e9montrent que beaucoup de chemin a \u00e9t\u00e9 parcouru dans les derni\u00e8res ann\u00e9es. \u00ab\u00a0Nous sommes \u00e0 m\u00eame d\u2019observer, au quotidien, qu\u2019il y a du changement positif. Les femmes s\u2019int\u00e9ressent autant au d\u00e9veloppement immobilier, qu\u2019\u00e0 la gestion ou au support professionnel\u00a0\u00bb, lance d\u2019entr\u00e9e de jeu Chantal Cousineau, associ\u00e9e, chef des services professionnels du secteur immobilier et construction chez BDO et membre du conseil d\u2019administration de CREW M. Elle note n\u00e9anmoins la pr\u00e9sence d\u2019une barri\u00e8re importante\u00a0: la force du r\u00e9seau. \u00ab\u00a0Les femmes accordent beaucoup d\u2019importance aux comp\u00e9tences. C\u2019est pourtant le r\u00e9seau qui nourrit le d\u00e9veloppement de carri\u00e8re.\u00a0\u00bb Et m\u00eame si de plus en plus d\u2019organisations se donnent comme mission de les soutenir, encore faut-il qu\u2019elles osent se lancer pour briser le plafond de verre.<\/p>\n<h3><strong>AUDACE<br \/>\n<\/strong><strong>NOM F\u00c9MININ (LATIN <em>AUDACIA<\/em>, DE <em>AUDERE<\/em>, <em>OSER<\/em>)<br \/>\nHARDIESSE QUI NE CONNA\u00ceT NI OBSTACLE NI LIMITE; COURAGE<\/strong><\/h3>\n<p>Nathalie Palladitcheff occupe depuis mars 2018 la pr\u00e9sidence d\u2019Ivanho\u00e9 Cambridge. Selon elle, un des \u00e9l\u00e9ments cl\u00e9s pour en \u00eatre arriv\u00e9e l\u00e0 est la confiance envers ses choix dont elle a su faire preuve. Elle admet du m\u00eame souffle que pour bien des femmes, cette capacit\u00e9 \u00e0 se faire confiance n\u2019est pas acquise\u00a0:\u00a0\u00ab\u00a0Nous sommes moins pr\u00e9par\u00e9es, en tant que jeunes filles ou jeunes femmes, \u00e0 nous faire confiance, \u00e0 avoir confiance en notre instinct, notre intuition, nos choix.\u00a0\u00bb Pourtant, bien des hommes qui vivent le succ\u00e8s dans leur carri\u00e8re font preuve d\u2019une confiance in\u00e9branlable, d\u2019audace et de cran. Et chez les femmes? \u00ab\u00a0On parle de fantaisie, on donne \u00e0 l\u2019audace une connotation quasi frivole ou m\u00eame n\u00e9gative, remarque la dirigeante. Un homme qui vit des aventures professionnelles diff\u00e9rentes sera vu comme audacieux et entreprenant. Dans ma g\u00e9n\u00e9ration, le fait d\u2019avoir le courage de ses opinions et de ses choix rend les femmes vuln\u00e9rables \u00e0 la critique. Et c\u2019est exactement l\u00e0 o\u00f9 il faut avoir confiance en soi.\u00a0\u00bb<\/p>\n<h3><strong>SUIVRE SON INSTINCT<\/strong><\/h3>\n<p>L\u2019audace, c\u2019est une chose. L\u2019intuition en est une autre. Et lorsqu\u2019on est une femme, cette petite voix int\u00e9rieure qui motive telle et telle d\u00e9cision est peut-\u00eatre plus difficile \u00e0 \u00e9couter. <a href=\"https:\/\/www.richter.ca\/fr\/experts\/stephanie-lincourt\/\" target=\"_blank\" rel=\"noopener noreferrer\">St\u00e9phanie Lincourt<\/a>, associ\u00e9e chez Richter, CPA auditrice qui se sp\u00e9cialise dans le domaine immobilier, n\u2019a jamais eu le sentiment qu\u2019on la traitait diff\u00e9remment parce qu\u2019elle \u00e9tait une femme. Par contre, elle admet qu\u2019il devient de plus en plus difficile de faire son chemin\u00a0:\u00a0\u00ab\u00a0On a des id\u00e9es diff\u00e9rentes et notre fa\u00e7on de communiquer l\u2019est aussi. Le plus difficile est sans doute de suivre son intuition et se faire confiance.\u00a0\u00bb \u00c2g\u00e9e de 39 ans, celle qui a aussi \u00e9t\u00e9 pr\u00e9sidente de CREW M reconna\u00eet qu\u2019\u00e0 ce titre, il y a une ouverture d\u2019esprit au Qu\u00e9bec qu\u2019on ne retrouve pas ailleurs au Canada ou aux \u00c9tats-Unis, m\u00eame s\u2019il reste encore quelques tabous dans certains milieux.<\/p>\n<h3><strong>LE POUVOIR DES NOUVELLES G\u00c9N\u00c9RATIONS<\/strong><\/h3>\n<p>La situation \u00e9volue pour le mieux, surtout que les mod\u00e8les de r\u00e9ussite se multiplient. Andr\u00e9e De Serres est titulaire de la Chaire Ivanho\u00e9 Cambridge d\u2019immobilier depuis 2011 et professeure \u00e0 l\u2019ESG UQAM. Dans son \u00e9quipe de chercheurs, assistants de recherche et professionnels, elle veille \u00e0 pr\u00e9server la parit\u00e9. Est-ce donc dire que les jeunes femmes sont moins expos\u00e9es \u00e0 la pr\u00e9dominance des hommes dans le monde de l\u2019immobilier? \u00ab\u00a0Il y a certainement une am\u00e9lioration, assure la chercheure qui croit beaucoup au potentiel de cette nouvelle vague. Plus on voit des femmes qui occupent des postes importants et qui sont visibles, plus \u00e7a stimule et encourage les jeunes \u00e0 s\u2019engager.\u00a0\u00bb La situation demeure toutefois largement in\u00e9galitaire\u00a0: les femmes sont encore sous repr\u00e9sent\u00e9es dans les m\u00e9tiers du courtage commercial et de la construction.<\/p>\n<h3><strong>GARDER LE CAP, ATTEINDRE SES OBJECTIFS<\/strong><\/h3>\n<p>Pour la nouvelle g\u00e9n\u00e9ration, rien n\u2019est impossible. Pourtant, bien des femmes, en d\u00e9but de carri\u00e8re, aspirent \u00e0 des postes d\u00e9cisionnels sans parvenir \u00e0 gravir les \u00e9chelons. \u00ab\u00a0Pourquoi ne pas encourager les jeunes femmes qui expriment une motivation au d\u00e9part? On les perd sur le chemin de la haute hi\u00e9rarchie, analyse Nathalie Palladitcheff\u00a0: dix ans plus tard, ce ne sont pas elles que l\u2019on voit sur les rangs de la vice-pr\u00e9sidence.\u00a0\u00bb Pour faire du secteur un milieu plus inclusif, un constat s\u2019impose. C\u2019est en ayant de plus en plus de femmes en t\u00eate de file que la parit\u00e9 sera atteinte. Parce que, pour les jeunes, ces femmes audacieuses deviennent des mod\u00e8les probants de r\u00e9ussite, des exemples dont le potentiel est non n\u00e9gligeable. Il ne faut donc pas sous-estimer la port\u00e9e de ces mod\u00e8les.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes. De la construction aux fonds d\u2019investissement, en passant par les communications et la gestion, elles font leur place, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1358],"class_list":["post-9666","insights","type-insights","status-publish","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter<\/title>\n<meta name=\"description\" content=\"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter\" \/>\n<meta property=\"og:description\" content=\"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-01T21:53:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\\\/\",\"name\":\"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2019-06-19T16:25:37+00:00\",\"dateModified\":\"2020-06-01T21:53:08+00:00\",\"description\":\"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter","description":"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter","og_description":"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2020-06-01T21:53:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/","name":"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2019-06-19T16:25:37+00:00","dateModified":"2020-06-01T21:53:08+00:00","description":"Article r\u00e9dig\u00e9 par Charles-\u00c9tienne Carrier et publi\u00e9 dans le magazine Premi\u00e8res en affaires. L\u2019immobilier regroupe un vaste champ de professions, et les L\u2019immobilier regroupe un vaste champ de professions, et les femmes parviennent graduellement \u00e0 se faire entendre dans ce milieu traditionnellement domin\u00e9 par les hommes.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/femmes-et-immobilier-la-partie-nest-pas-encore-gagnee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Dans les manchettes | Premi\u00e8res en affaires | St\u00e9phanie Lincourt cit\u00e9e dans un article sur les femmes en immobilier"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/9666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=9666"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=9666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}