{"id":9926,"date":"2018-07-03T19:01:05","date_gmt":"2018-07-03T17:01:05","guid":{"rendered":"https:\/\/www.richter.ca\/?post_type=medianews&#038;p=9926"},"modified":"2020-06-03T22:59:08","modified_gmt":"2020-06-03T20:59:08","slug":"lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb","status":"publish","type":"insights","link":"https:\/\/www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/","title":{"rendered":"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb"},"content":{"rendered":"<p><strong><em>Cet article a initialement \u00e9t\u00e9 publi\u00e9 dans Espace Montr\u00e9al, Volume 27, #2, 2018.<\/em><\/strong><\/p>\n<p>Plusieurs gestionnaires, investisseurs immobiliers ainsi que leur famille ont investi dans de nouvelles constructions ou des r\u00e9novations de condominium dans le but d\u2019obtenir des revenus d\u2019h\u00e9bergement \u00e0 court terme, centr\u00e9 plus particuli\u00e8rement sur le tourisme et les \u00e9tudiants \u00e9trangers.<\/p>\n<p>L\u2019industrie de l\u2019h\u00e9bergement est soumise \u00e0 une r\u00e9glementation particuli\u00e8re et une fiscalit\u00e9 qui lui est propre. On peut penser notamment aux r\u00e8gles de TPS\/TVQ (l\u2019h\u00e9bergement court terme est g\u00e9n\u00e9ralement taxable alors que la location r\u00e9sidentielle long terme est exon\u00e9r\u00e9e) et la taxe sur l\u2019h\u00e9bergement.<\/p>\n<p>Une entreprise qui veut \u0153uvrer dans le domaine de l\u2019h\u00e9bergement court terme, tel qu\u2019un h\u00f4tel, une auberge ou autre g\u00eete semblable, doit g\u00e9n\u00e9ralement obtenir les licences et permis requis ainsi que s\u2019inscrire aux fins de lois fiscales et percevoir les taxes appropri\u00e9es.<\/p>\n<p>L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. En r\u00e9sum\u00e9, l\u2019\u00e9conomie collaborative, aussi appel\u00e9e l\u2019\u00e9conomie du partage, est un mod\u00e8le socio-\u00e9conomique qui repose sur le partage ou l\u2019\u00e9change de biens, de services ou de connaissances entre particuliers. Elle se traduit par un \u00e9change mon\u00e9taire tel que la vente, la location ou la prestation de services, ou un \u00e9change non mon\u00e9taire comme le troc, le don ou le volontariat. Dans ce syst\u00e8me \u00e9conomique, les particuliers sont g\u00e9n\u00e9ralement mis en relation via des plateformes num\u00e9riques. Plusieurs entreprises ont bas\u00e9 leur r\u00e9ussite sur ce type d\u2019\u00e9conomie et sont devenues des acteurs majeurs au niveau international. On peut penser notamment \u00e0 des entreprises telles qu\u2019Uber ou Airbnb.<\/p>\n<p>Face \u00e0 l&rsquo;essor de l&rsquo;\u00e9conomie collaborative et \u00e0 l&rsquo;augmentation des transactions entre particuliers, plusieurs associations et regroupements ont commenc\u00e9 \u00e0 souligner les effets n\u00e9gatifs sur leur industrie. On peut penser notamment \u00e0 l\u2019industrie du taxi qui a vu d\u2019un mauvais \u0153il la concurrence des chauffeurs d\u2019Uber.<\/p>\n<p>M\u00eame chose de la part de l\u2019industrie de l\u2019h\u00e9bergement \u00e0 l\u2019\u00e9gard des plateformes comme Airbnb. On y d\u00e9plore que la prolif\u00e9ration de l\u2019offre de logements \u00e0 partir de ces plateformes cr\u00e9e de la concurrence d\u00e9loyale, des frictions entre les touristes et les r\u00e9sidents et retire du march\u00e9 des logements \u00e0 louer \u00e0 plus long terme. De plus, un nombre croissant de personnes qui utilisent ces plateformes ignorent ou comprennent mal les obligations r\u00e9glementaires et fiscales pouvant s&rsquo;appliquer \u00e0 leur situation.<\/p>\n<p>Cette m\u00e9connaissance des lois en vigueur pose des d\u00e9fis importants pour l\u2019industrie de l\u2019h\u00e9bergement touristique, la soci\u00e9t\u00e9 et les administrations fiscales, dont notamment un risque accru de non-conformit\u00e9 fiscale.<\/p>\n<h2><strong>Actions du gouvernement du Qu\u00e9bec<\/strong><\/h2>\n<p>Le gouvernement du Qu\u00e9bec a entrepris des d\u00e9marches afin de s\u2019assurer que les initiatives li\u00e9es \u00e0 la nouvelle \u00e9conomie soient encadr\u00e9es par une r\u00e9glementation et une l\u00e9gislation qui pr\u00e9servent l\u2019\u00e9quilibre entre l\u2019innovation, la s\u00e9curit\u00e9 et l\u2019\u00e9quit\u00e9. Ainsi, Qu\u00e9bec souhaite encourager l\u2019\u00e9conomie du partage dans la mesure o\u00f9 elle respecte les lois fiscales et les droits des travailleurs.<\/p>\n<p>Le gouvernement du Qu\u00e9bec a indiqu\u00e9 qu\u2019il entend adopter une approche d\u2019ouverture et offrir \u00e0 l\u2019\u00e9conomie collaborative un encadrement appropri\u00e9, tenant \u00e9galement compte des activit\u00e9s dites traditionnelles et \u00e9quitables envers celles-ci.<\/p>\n<p>Des modifications ont donc \u00e9t\u00e9 apport\u00e9es d\u00e8s octobre 2015 \u00e0 la <em>Loi sur les \u00e9tablissements d\u2019h\u00e9bergement touristique<\/em> afin de permettre un all\u00e9gement des proc\u00e9dures auxquelles sont soumis les exploitants d\u2019\u00e9tablissement d\u2019h\u00e9bergement touristique pour la d\u00e9livrance de classifications et de bonifier les pouvoirs d\u2019enqu\u00eate et d\u2019inspection du minist\u00e8re du Tourisme pour assurer la conformit\u00e9 avec cette loi. Comme nous le verrons plus loin, ces pouvoirs d\u2019enqu\u00eate et d\u2019inspection ont \u00e9t\u00e9 transf\u00e9r\u00e9s \u00e0 Revenu Qu\u00e9bec en 2018 dans le cadre du projet de 150. Les changements \u00e0 la loi avaient notamment pour but de faciliter la conformit\u00e9 pour les personnes offrant de l\u2019h\u00e9bergement touristique par l\u2019interm\u00e9diaire des plateformes d\u2019\u00e9conomie collaborative.<\/p>\n<p>Par la suite, plusieurs autres d\u00e9marches ont \u00e9t\u00e9 entreprises par le gouvernement du Qu\u00e9bec dont notamment les suivantes\u00a0:<\/p>\n<ol>\n<li>Le 21 juillet 2017, Revenu Qu\u00e9bec et le minist\u00e8re du Tourisme ont sign\u00e9 une entente avec Airbnb. Nous verrons plus loin les d\u00e9tails de cette entente.<\/li>\n<li>En novembre 2017, Qu\u00e9bec pr\u00e9sentait son plan \u00e9conomique, <em>Paradis fiscaux\u00a0: plan d\u2019action pour assurer l\u2019\u00e9quit\u00e9 fiscale<\/em>, dans lequel on y indique l\u2019approche face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative telle que mentionn\u00e9e ci-dessus.<\/li>\n<li>Le 9 f\u00e9vrier 2018, Qu\u00e9bec a annonc\u00e9 la cr\u00e9ation d\u2019un groupe de travail sur l\u2019\u00e9conomie collaborative dont le pr\u00e9sident est Guillaume Lavoie (ancien conseiller municipal de Projet Montr\u00e9al), la PDG de la Chambre de commerce de l\u2019est de Montr\u00e9al et d\u2019une professeure de l\u2019Universit\u00e9 Laval. Le groupe devait se pencher sur les actions les plus efficaces afin d\u2019int\u00e9grer de fa\u00e7on harmonieuse les transformations qu\u2019am\u00e8ne l\u2019\u00e9conomie collaborative.<\/li>\n<li>Le 12 juin 2018, le groupe de travail a d\u00e9pos\u00e9 son rapport. Dans les recommandations du groupe, on y indique notamment que la location d\u2019h\u00e9bergement par l\u2019entremise de plateformes devrait se limiter \u00e0 la r\u00e9sidence principale. S\u2019inspirant des exemples de New York, Toronto et Vancouver, le groupe de recherche propose de cr\u00e9er un syst\u00e8me d\u2019enregistrement en ligne qui permettrait \u00e0 la personne qui souhaite louer sa r\u00e9sidence principale d\u2019obtenir un num\u00e9ro d\u2019identification et de le divulguer pour chaque offre de location. Le but serait d\u2019\u00e9viter que des entreprises et des particuliers ach\u00e8tent des condominiums ou louent des logements dans le seul but de les louer sur Airbnb ou autres plateformes semblables.<\/li>\n<li>Le m\u00eame jour, le projet de loi 150 a \u00e9t\u00e9 adopt\u00e9. Ce projet de loi inclut des modifications \u00e0 la <em>Loi sur les \u00e9tablissements d\u2019h\u00e9bergement touristique<\/em> et permet \u00e9galement \u00e0 une entreprise op\u00e9rant une plateforme d\u2019\u00e9conomie collaborative de s\u2019inscrire de fa\u00e7on volontaire afin de percevoir et remettre la taxe sur l\u2019h\u00e9bergement.<\/li>\n<\/ol>\n<h2><strong>Entente avec Airbnb et le projet de loi 150 \u00a0<\/strong><\/h2>\n<p>Tel que mentionn\u00e9 ci-dessus, Revenu Qu\u00e9bec, le minist\u00e8re du Tourisme et Airbnb ont sign\u00e9 une entente en date du 21 juillet 2017. Cette entente a \u00e9t\u00e9 rendue publique au mois d\u2019ao\u00fbt 2017. Il s\u2019agit du tout premier accord fiscal de ce genre au Canada. De par son r\u00f4le limit\u00e9 (la mise \u00e0 la disposition de sa plateforme num\u00e9rique), Airbnb n\u2019est ni exploitant d\u2019un \u00e9tablissement d\u2019h\u00e9bergement ni un interm\u00e9diaire au sens de la loi pour l\u2019application de la taxe sur l\u2019h\u00e9bergement. Par cons\u00e9quent, Airbnb n\u2019a pas d\u2019obligation l\u00e9gale de payer, de percevoir ou de remettre la taxe sur l\u2019h\u00e9bergement \u00e0 l\u2019\u00e9gard des fournitures d\u2019unit\u00e9s d\u2019h\u00e9bergement offertes au Qu\u00e9bec par les h\u00f4tes par l\u2019entremise de sa plateforme.<\/p>\n<p>En vertu \u00a0de cette entente, Airbnb a accept\u00e9 volontairement de s\u2019inscrire aux fins de la taxe sur l\u2019h\u00e9bergement et de percevoir et remettre cette taxe \u00e0 Revenu Qu\u00e9bec \u00e0 titre de mandataire pour les h\u00f4tes \u00e0 compter du 1<sup>er<\/sup> octobre 2017. De leur c\u00f4t\u00e9, les h\u00f4tes qui offrent des unit\u00e9s d\u2019h\u00e9bergement uniquement par l\u2019entremise de la plateforme Airbnb ne seront pas tenus d\u2019\u00eatre inscrits pour la taxe sur l\u2019h\u00e9bergement.<\/p>\n<p>Avec cette entente, il semble que Qu\u00e9bec y voit des avantages d\u2019un point de vue administratif et de conformit\u00e9 fiscale \u00e9tant donn\u00e9 que Revenu Qu\u00e9bec n\u2019aura \u00e0 traiter qu\u2019avec une seule personne (Airbnb) en ce qui concerne la perception et la remise de la taxe sur l\u2019h\u00e9bergement au lieu de plusieurs milliers d\u2019h\u00f4tes qui utilisent cette plateforme. En plus, l\u2019entente pr\u00e9voit le partage d\u2019information qui permettra \u00e0 Revenu Qu\u00e9bec d\u2019avoir acc\u00e8s aux renseignements concernant les h\u00f4tes et pourra ainsi proc\u00e9der \u00e0 des v\u00e9rifications fiscales de ces personnes pour les fins d\u2019autres lois fiscales, dont la TPS\/TVQ et l\u2019imp\u00f4t sur le revenu.<\/p>\n<p>De son c\u00f4t\u00e9, Airbnb a indiqu\u00e9 qu\u2019il s\u2019agissait d\u2019un bel exemple de partenariat avec le gouvernement et cette entente imitait un mod\u00e8le d\u00e9j\u00e0 mis en place ailleurs dans le monde. Il est raisonnable de croire qu\u2019une des motivations d\u2019Airbnb \u00e0 signer ce genre d\u2019entente est de faciliter la vie de ses usagers (les h\u00f4tes) puisque ces derniers n\u2019auront pas \u00e0 s\u2019inscrire ou \u00e0 percevoir et remettre la taxe sur l\u2019h\u00e9bergement.<\/p>\n<p>Il faut se rappeler que l&rsquo;industrie s&rsquo;est longtemps plainte que les services d&rsquo;Airbnb constituaient une concurrence d\u00e9loyale pour elle et Qu\u00e9bec avait adopt\u00e9 la loi 67 au printemps 2016 qui exigeait que les locateurs d&rsquo;Airbnb per\u00e7oivent la taxe sur l&rsquo;h\u00e9bergement et obtiennent une attestation officielle de Tourisme Qu\u00e9bec. Le gouvernement avait aussi d\u00e9sign\u00e9 18 enqu\u00eateurs pour s&rsquo;assurer que ces nouvelles exigences \u00e9taient respect\u00e9es, mais sans toutefois obtenir un grand succ\u00e8s. Au moment de signer cette entente, Airbnb avait environ 22 000 logements offerts par des locateurs du Qu\u00e9bec sur sa plateforme, dont une moiti\u00e9 se trouvait dans la r\u00e9gion de Montr\u00e9al.<\/p>\n<p>Un autre aspect important du comportement \u00ab\u00a0bon citoyen corporatif\u00a0\u00bb est qu\u2019Airbnb fait \u00e9galement face \u00e0 un mouvement de certaines villes dans le monde qui optent pour interdire la location de r\u00e9sidences par l\u2019entremise de ces plateformes sur leur territoire. Bien que Montr\u00e9al n\u2019ait pas encore embo\u00eet\u00e9 le pas, il faut souligner que l\u2019arrondissement Ville-Marie a adopt\u00e9 de nouvelles r\u00e8gles le 12 juin 2018 visant \u00e0 limiter le nombre de locations r\u00e9sidentielles \u00e0 court terme dans le centre-ville de Montr\u00e9al. Le nouveau r\u00e8glement vise \u00e0 restreindre les locations touristiques priv\u00e9es telles que celles offertes sur le site Airbnb. Les r\u00e8gles limiteront les nouvelles locations sur un tron\u00e7on de 3,3 kilom\u00e8tres le long de la rue Sainte-Catherine et emp\u00eacheront l\u2019ouverture de nouvelles r\u00e9sidences de tourisme \u00e0 moins de 150 m\u00e8tres l\u2019une de l\u2019autre. Face \u00e0 cette annonce, Airbnb a d\u00e9clar\u00e9 dans un communiqu\u00e9 vouloir travailler avec la Ville de Montr\u00e9al pour s\u2019assurer que le nouveau r\u00e8glement tienne compte \u00e0 la fois des probl\u00e8mes d\u2019accessibilit\u00e9 et des droits des personnes \u00e0 partager leur logement.<\/p>\n<p>Avec l\u2019adoption du projet de loi 150, Qu\u00e9bec a fait des modifications \u00e0 la taxe sur l\u2019h\u00e9bergement et permet maintenant aux entreprises de l\u2019\u00e9conomie collaborative ayant des plateformes num\u00e9riques permettant la location d\u2019h\u00e9bergement \u00e0 court terme de s\u2019inscrire de fa\u00e7on volontaire et de percevoir la taxe sur l\u2019h\u00e9bergement. Essentiellement, les modifications font en sorte que les autres entreprises de l\u2019\u00e9conomie collaborative puissent maintenant obtenir des conditions semblables \u00e0 celles octroy\u00e9es par Qu\u00e9bec \u00e0 Airbnb. De plus, les pouvoirs d\u2019enqu\u00eate et d\u2019inspection qui relevaient auparavant du minist\u00e8re du Tourisme ont \u00e9t\u00e9 transf\u00e9r\u00e9s \u00e0 Revenu Qu\u00e9bec. Il est \u00e0 pr\u00e9voir que les actions de Revenu Qu\u00e9bec auront probablement plus d\u2019impact que celles du minist\u00e8re du Tourisme.<\/p>\n<p>Revenu Qu\u00e9bec a notamment annonc\u00e9 le 13 juin 2018 par communiqu\u00e9 qu\u2019il commencera ses activit\u00e9s de sensibilisation, d\u2019inspection et d\u2019enqu\u00eate dans le secteur de l\u2019h\u00e9bergement touristique avec une \u00e9quipe de 25 personnes afin de notamment lutter contre l\u2019h\u00e9bergement ill\u00e9gal et d\u2019assurer le respect des obligations fiscales des exploitants. \u00c0 cet effet, Revenu Qu\u00e9bec a publi\u00e9 le guide IN-259, <em>Inspection des \u00e9tablissements d\u2019h\u00e9bergement touristique<\/em>, qui r\u00e9sume les obligations des exploitants, du d\u00e9roulement des inspections et des amendes et sanctions en cas d\u2019omissions.<\/p>\n<h2><strong>Obligations fiscales des personnes offrant de l\u2019h\u00e9bergement touristique par l\u2019interm\u00e9diaire des plateformes d\u2019\u00e9conomie collaborative<\/strong><\/h2>\n<p>Une personne qui loue des unit\u00e9s d\u2019h\u00e9bergement touristique \u00e0 des clients par l\u2019interm\u00e9diaire d\u2019une plateforme d\u2019\u00e9conomie collaborative doit s\u2019inscrire et percevoir la TPS\/TVQ \u00e0 moins d\u2019\u00eatre consid\u00e9r\u00e9e comme un petit fournisseur (c\u2019est-\u00e0-dire 30 000$ ou moins de fournitures taxables au cours d\u2019une p\u00e9riode de 12 mois). Cette personne doit \u00e9galement inclure les revenus provenant de cette location dans sa d\u00e9claration de revenus pour les fins de l\u2019imp\u00f4t.<\/p>\n<p>De plus, \u00e0 moins que la plateforme d\u2019\u00e9conomie collaborative soit inscrite aux fins de la taxe sur l\u2019h\u00e9bergement, la personne qui exploite un \u00e9tablissement d\u2019h\u00e9bergement touristique situ\u00e9 dans une r\u00e9gion touristique o\u00f9 cette taxe s\u2019applique doit s\u2019inscrire, percevoir et remettre cette taxe sur chaque unit\u00e9 d\u2019h\u00e9bergement lou\u00e9 \u00e0 un client. Prenez note que la notion de petit fournisseur en TPS\/TVQ ne s\u2019applique pas dans le cas de la taxe sur l\u2019h\u00e9bergement.<\/p>\n<p>L\u2019expression \u00ab\u00a0\u00e9tablissement d\u2019h\u00e9bergement touristique\u00a0\u00bb a le sens que lui donne le <em>R\u00e8glement sur les \u00e9tablissements d\u2019h\u00e9bergement touristique<\/em>, c\u2019est-\u00e0-dire qu\u2019elle d\u00e9signe tout \u00e9tablissement dans lequel au moins une unit\u00e9 d\u2019h\u00e9bergement est offerte en location contre r\u00e9mun\u00e9ration, pour une p\u00e9riode n\u2019exc\u00e9dant pas 31 jours, \u00e0 des touristes sur une base r\u00e9guli\u00e8re et dont la disponibilit\u00e9 de l\u2019unit\u00e9 est rendue publique.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.<\/p>\n","protected":false},"featured_media":0,"template":"","insights-type":[1358],"class_list":["post-9926","insights","type-insights","status-publish","hentry","insights-type-nouvelles-la-vie-chez-richter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter<\/title>\n<meta name=\"description\" content=\"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter\" \/>\n<meta property=\"og:description\" content=\"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/\" \/>\n<meta property=\"og:site_name\" content=\"Richter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Richtercanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-03T20:59:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@richtercanada\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\\\/\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\\\/\",\"name\":\"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\"},\"datePublished\":\"2018-07-03T17:01:05+00:00\",\"dateModified\":\"2020-06-03T20:59:08+00:00\",\"description\":\"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Richter\",\"item\":\"https:\\\/\\\/www.richter.ca\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/www.www.richter.ca\\\/fr\\\/nos-reflexions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"name\":\"Richter\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.www.richter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#organization\",\"name\":\"Richter\",\"url\":\"https:\\\/\\\/www.www.richter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/richterca.tor1.digitaloceanspaces.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo.png\",\"width\":128,\"height\":24,\"caption\":\"Richter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.www.richter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Richtercanada\\\/\",\"https:\\\/\\\/x.com\\\/richtercanada\",\"https:\\\/\\\/www.instagram.com\\\/richtercanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/richter\\\/?trk=hb_tab_compy_id_255303\"],\"address\":[{\"@type\":\"PostalAddress\",\"addressLocality\":\"Montreal, QC, Canada\",\"postalCode\":\"H3A 0G6\",\"streetAddress\":\"1981 McGill College, #1100 The Richter Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Toronto, ON, Canada\",\"postalCode\":\"M5J 2T3\",\"streetAddress\":\"181 Bay St. #3510 Bay Wellington Tower\"},{\"@type\":\"PostalAddress\",\"addressLocality\":\"Chicago, IL, United States\",\"postalCode\":\"60606\",\"streetAddress\":\"200 South Wacker, #3100\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"telephone\":\"+1-514-934-3400\",\"contactType\":\"Montreal office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-416-488-2345\",\"contactType\":\"Toronto office\"},{\"@type\":\"ContactPoint\",\"telephone\":\"+1-312-828-0800\",\"contactType\":\"Chicago office\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter","description":"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter","og_description":"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.","og_url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/","og_site_name":"Richter","article_publisher":"https:\/\/www.facebook.com\/Richtercanada\/","article_modified_time":"2020-06-03T20:59:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2026\/05\/web_landing_page_image_100th_emblem_1200x630px1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@richtercanada","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/","url":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/","name":"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb - Richter","isPartOf":{"@id":"https:\/\/www.www.richter.ca\/#website"},"datePublished":"2018-07-03T17:01:05+00:00","dateModified":"2020-06-03T20:59:08+00:00","description":"L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es. L\u2019av\u00e8nement du commerce \u00e9lectronique et de l\u2019\u00e9conomie collaborative sont venus bouleverser les fa\u00e7ons de faire et le mod\u00e8le \u00e9conomique traditionnel auquel les entreprises \u00e9taient habitu\u00e9es.","breadcrumb":{"@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/lapproche-du-quebec-face-a-lenjeu-de-leconomie-collaborative-et-les-entreprises-telles-quairbnb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Richter","item":"https:\/\/www.richter.ca\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/www.www.richter.ca\/fr\/nos-reflexions\/"},{"@type":"ListItem","position":3,"name":"Dans les manchettes | Espace | Stephane Marcassa | Qu\u00e9bec face \u00e0 l\u2019enjeu de l\u2019\u00e9conomie collaborative et les entreprises telles qu\u2019Airbnb"}]},{"@type":"WebSite","@id":"https:\/\/www.www.richter.ca\/#website","url":"https:\/\/www.www.richter.ca\/","name":"Richter","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/www.www.richter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.www.richter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.www.richter.ca\/#organization","name":"Richter","url":"https:\/\/www.www.richter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","contentUrl":"https:\/\/richterca.tor1.digitaloceanspaces.com\/wp-content\/uploads\/2018\/08\/logo.png","width":128,"height":24,"caption":"Richter"},"image":{"@id":"https:\/\/www.www.richter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Richtercanada\/","https:\/\/x.com\/richtercanada","https:\/\/www.instagram.com\/richtercanada","https:\/\/www.linkedin.com\/company\/richter\/?trk=hb_tab_compy_id_255303"],"address":[{"@type":"PostalAddress","addressLocality":"Montreal, QC, Canada","postalCode":"H3A 0G6","streetAddress":"1981 McGill College, #1100 The Richter Tower"},{"@type":"PostalAddress","addressLocality":"Toronto, ON, Canada","postalCode":"M5J 2T3","streetAddress":"181 Bay St. #3510 Bay Wellington Tower"},{"@type":"PostalAddress","addressLocality":"Chicago, IL, United States","postalCode":"60606","streetAddress":"200 South Wacker, #3100"}],"contactPoint":[{"@type":"ContactPoint","telephone":"+1-514-934-3400","contactType":"Montreal office"},{"@type":"ContactPoint","telephone":"+1-416-488-2345","contactType":"Toronto office"},{"@type":"ContactPoint","telephone":"+1-312-828-0800","contactType":"Chicago office"}]}]}},"_links":{"self":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights\/9926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/types\/insights"}],"wp:attachment":[{"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/media?parent=9926"}],"wp:term":[{"taxonomy":"insights-type","embeddable":true,"href":"https:\/\/www.richter.ca\/fr\/wp-json\/wp\/v2\/insights-type?post=9926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}